{"id":5860,"date":"2022-04-02T15:12:36","date_gmt":"2022-04-02T15:12:36","guid":{"rendered":"https:\/\/www.griffinmachinery.com\/essiccatore-a-spruzzo-centrifugo\/"},"modified":"2023-04-05T16:02:49","modified_gmt":"2023-04-05T16:02:49","slug":"nebulizzatore-centrifugo","status":"publish","type":"product","link":"https:\/\/www.griffinmachinery.com\/it\/nebulizzatore-centrifugo\/","title":{"rendered":"Essiccatore a Spruzzo Centrifugo"},"content":{"rendered":"<h2 style=\"text-align: center;\">Diagramma di flusso dell&#8217;essiccatore a spruzzo centrifugo<\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-11047\" src=\"https:\/\/www.griffinmachinery.com\/wp-content\/uploads\/2022\/04\/Diagramma-di-flusso-dellessiccatore-a-spruzzo-centrifugo.jpg\" alt=\"Diagramma di flusso dell'essiccatore a spruzzo centrifugo\" width=\"1394\" height=\"890\" srcset=\"https:\/\/www.griffinmachinery.com\/wp-content\/uploads\/2022\/04\/Diagramma-di-flusso-dellessiccatore-a-spruzzo-centrifugo.jpg 1394w, https:\/\/www.griffinmachinery.com\/wp-content\/uploads\/2022\/04\/Diagramma-di-flusso-dellessiccatore-a-spruzzo-centrifugo-300x192.jpg 300w, https:\/\/www.griffinmachinery.com\/wp-content\/uploads\/2022\/04\/Diagramma-di-flusso-dellessiccatore-a-spruzzo-centrifugo-1024x654.jpg 1024w, https:\/\/www.griffinmachinery.com\/wp-content\/uploads\/2022\/04\/Diagramma-di-flusso-dellessiccatore-a-spruzzo-centrifugo-768x490.jpg 768w, https:\/\/www.griffinmachinery.com\/wp-content\/uploads\/2022\/04\/Diagramma-di-flusso-dellessiccatore-a-spruzzo-centrifugo-600x383.jpg 600w\" sizes=\"auto, (max-width: 1394px) 100vw, 1394px\" \/><\/p>\n<hr \/>\n<h2 style=\"text-align: center;\">Parametri tecnici<\/h2>\n<table class=\"table\" border=\"1\" width=\"100%\" cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr class=\"firstRow\">\n<td bgcolor=\"#d9edf7\" width=\"228\">Dimensione del modello<\/td>\n<td width=\"123\">5<\/td>\n<td width=\"91\">25<\/td>\n<td width=\"65\">50<\/td>\n<td width=\"45\">150<\/td>\n<td width=\"137\">200-2000<\/td>\n<\/tr>\n<tr>\n<td bgcolor=\"#d9edf7\" width=\"228\">Temperatura di ingresso<\/td>\n<td style=\"text-align: center;\" colspan=\"5\" width=\"460\">Controllo automatico 140-350 \u2103<\/td>\n<\/tr>\n<tr>\n<td bgcolor=\"#d9edf7\" width=\"228\">Temperatura di uscita<\/td>\n<td style=\"text-align: center;\" colspan=\"5\" width=\"460\">80-90\u2103<\/td>\n<\/tr>\n<tr>\n<td bgcolor=\"#d9edf7\" width=\"228\">Max. Capacit\u00e0 di evaporazione (kg\/h)<\/td>\n<td width=\"123\">5<\/td>\n<td width=\"91\">25<\/td>\n<td width=\"65\">50<\/td>\n<td width=\"45\">150<\/td>\n<td width=\"137\">200-2000<\/td>\n<\/tr>\n<tr>\n<td bgcolor=\"#d9edf7\" width=\"228\">Metodo di atomizzazione<\/td>\n<td width=\"123\">trasmissione di aria compressa<\/td>\n<td style=\"text-align: center;\" colspan=\"4\" width=\"337\">trasmissione meccanica<\/td>\n<\/tr>\n<tr>\n<td bgcolor=\"#d9edf7\" width=\"228\">Rivoluzione(r.p.m)<\/td>\n<td width=\"123\">25000<\/td>\n<td width=\"91\">18000<\/td>\n<td width=\"65\">18000<\/td>\n<td width=\"45\">15000<\/td>\n<td width=\"137\">8000-15000<\/td>\n<\/tr>\n<tr>\n<td bgcolor=\"#d9edf7\" width=\"228\">Diametro del disco d&#8217;atomizzazione (millimetro)<\/td>\n<td width=\"123\">50<\/td>\n<td width=\"91\">120<\/td>\n<td width=\"65\">120<\/td>\n<td width=\"45\">150<\/td>\n<td width=\"137\">180-240<\/td>\n<\/tr>\n<tr>\n<td bgcolor=\"#d9edf7\" width=\"228\">Fonte di calore<\/td>\n<td width=\"123\">elettricit\u00e0<\/td>\n<td width=\"91\">vapore+elettricit\u00e0<\/td>\n<td style=\"text-align: center;\" colspan=\"3\" width=\"247\">vapore+elettricit\u00e0, olio, olio combustibile, forno ad aria calda<\/td>\n<\/tr>\n<tr>\n<td bgcolor=\"#d9edf7\" width=\"228\">Max. Potenza di riscaldamento (kW)<\/td>\n<td width=\"123\">9<\/td>\n<td width=\"91\">36<\/td>\n<td width=\"65\">72<\/td>\n<td width=\"45\">99<\/td>\n<td width=\"137\"><\/td>\n<\/tr>\n<tr>\n<td bgcolor=\"#d9edf7\" width=\"228\">Dimensioni complessive (L*W*H)(m)<\/td>\n<td width=\"123\">1.8\u00d70.93\u00d72.2<\/td>\n<td width=\"91\">3\u00d72.7\u00d74.26<\/td>\n<td width=\"65\">3.5\u00d73.5\u00d74.8<\/td>\n<td width=\"45\">5.5\u00d74\u00d77<\/td>\n<td width=\"137\">dipende dalla situazione reale<\/td>\n<\/tr>\n<tr>\n<td bgcolor=\"#d9edf7\" width=\"228\">Tasso di ripristino della polvere secca (%)<\/td>\n<td style=\"text-align: center;\" colspan=\"5\" width=\"460\">\u226595<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<hr \/>\n<h2 style=\"text-align: center;\">Composizione Della Macchina Di Essiccazione Centrifuga A Spruzzo<\/h2>\n<h3>1. Sistema di alimentazione<\/h3>\n<p>1.5kw, 0.8mpA motore pompa a vite a frequenza variabile, la temperatura di progettazione \u00e8 in condizioni di temperatura normale, se c&#8217;\u00e8 un cambiamento di temperatura, si prega di contattarci.<\/p>\n<h3>2. Sistema ad aria calda<\/h3>\n<p>Questo sistema fornisce l&#8217;aria pulita necessaria prima dell&#8217;essiccazione. Il volume di filtrazione \u00e8 di 25000m3\/h e la pressione massima \u00e8 di 50Pa. Il materiale del filtro \u00e8 in tessuto non tessuto e il sistema di riscaldamento adotta vapore + riscaldamento elettrico.<\/p>\n<h3>3. Sistema di essiccazione<\/h3>\n<p><strong>3.1 Voluta di ingresso<\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-8968 size-medium\" src=\"https:\/\/www.griffinmachinery.com\/wp-content\/uploads\/2022\/04\/Centrifugal-Spray-Dry-Inlet-Volute-300x226.png\" alt=\"Centrifugal Spray Dry Inlet Volute\" width=\"300\" height=\"226\" srcset=\"https:\/\/www.griffinmachinery.com\/wp-content\/uploads\/2022\/04\/Centrifugal-Spray-Dry-Inlet-Volute-300x226.png 300w, https:\/\/www.griffinmachinery.com\/wp-content\/uploads\/2022\/04\/Centrifugal-Spray-Dry-Inlet-Volute.png 338w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p>La voluta dell&#8217;aria calda a spirale logaritmica in acciaio inox SUS304 si trova nella parte superiore della torre di essiccazione e fornisce aria calda stabile alla torre di essiccazione.<\/p>\n<p><strong>3.2 Torre di essiccazione<\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-8998 size-full\" src=\"https:\/\/www.griffinmachinery.com\/wp-content\/uploads\/2022\/04\/Centrifugal-Spray-Dry-Drying-Tower.png\" alt=\"Centrifugal Spray Dry Drying Tower\" width=\"284\" height=\"364\" srcset=\"https:\/\/www.griffinmachinery.com\/wp-content\/uploads\/2022\/04\/Centrifugal-Spray-Dry-Drying-Tower.png 284w, https:\/\/www.griffinmachinery.com\/wp-content\/uploads\/2022\/04\/Centrifugal-Spray-Dry-Drying-Tower-234x300.png 234w\" sizes=\"auto, (max-width: 284px) 100vw, 284px\" \/><\/p>\n<p>La torre di essiccazione \u00e8 un cilindro alto con fondo conico. La torre \u00e8 dotata di ingresso e uscita dell&#8217;aria calda, porte di ispezione e pulizia, fori di osservazione, fori di illuminazione, ecc. L&#8217;intera torre di essiccazione \u00e8 montata su una staffa.<\/p>\n<p>Le pareti interne ed esterne della torre sono realizzate in acciaio inox SUS304. Il materiale isolante \u00e8 silicato di alluminio da 100 mm (Al\u2082SiO\u2085).<\/p>\n<hr \/>\n<h2 style=\"text-align: center;\">Applicazioni<\/h2>\n<p><strong>1. La nostra soluzione essiccante per essiccatore a spruzzo centrifugo LPG-200 per composti nutritivi<\/strong><\/p>\n<div class=\"wptb-container-legacy\" data-table-id=\"9274\">\n    <table class=\"wptb-preview-table wptb-element-main-table_setting-2909 edit-active\" data-reconstraction=\"0\" style=\"border: 1px solid rgb(216, 216, 216); display: table;\" data-wptb-table-tds-sum-max-width=\"263.5\" data-wptb-cells-width-auto-count=\"2\" role=\"table\" data-wptb-header-background-color=\"#ffffff\" data-table-columns=\"2\" data-wptb-table-directives=\"eyJpbm5lckJvcmRlcnMiOnsiYWN0aXZlIjoiYWxsIiwiYm9yZGVyV2lkdGgiOiIxIiwiYm9yZGVyUmFkaXVzZXMiOnsiYWxsIjpudWxsfX19\" data-wptb-extra-styles=\"LndwdGItcmliYm9uX2VsZW1lbnQtY29udGFpbmVyIHsKICB0b3A6IC03JTsKfQogIA==\" data-wptb-responsive-directives=\"eyJyZXNwb25zaXZlRW5hYmxlZCI6dHJ1ZSwicmVzcG9uc2l2ZU1vZGUiOiJhdXRvIiwicHJlc2VydmVSb3dDb2xvciI6ZmFsc2UsInJlbGF0aXZlV2lkdGgiOiJ3aW5kb3ciLCJoZWFkZXJGdWxseU1lcmdlZCI6ZmFsc2UsIm1vZGVPcHRpb25zIjp7ImF1dG8iOnsiZGlzYWJsZWQiOnsiZGVza3RvcCI6ZmFsc2UsInRhYmxldCI6ZmFsc2UsIm1vYmlsZSI6ZmFsc2V9LCJ0b3BSb3dBc0hlYWRlciI6eyJkZXNrdG9wIjpmYWxzZSwidGFibGV0Ijp0cnVlLCJtb2JpbGUiOmZhbHNlfSwicmVwZWF0TWVyZ2VkSGVhZGVyIjp7ImRlc2t0b3AiOnRydWUsInRhYmxldCI6dHJ1ZSwibW9iaWxlIjp0cnVlfSwic3RhdGljVG9wUm93Ijp7ImRlc2t0b3AiOmZhbHNlLCJ0YWJsZXQiOmZhbHNlLCJtb2JpbGUiOmZhbHNlfSwiY2VsbFN0YWNrRGlyZWN0aW9uIjp7ImRlc2t0b3AiOiJyb3ciLCJ0YWJsZXQiOiJyb3ciLCJtb2JpbGUiOiJjb2x1bW4ifSwiY2VsbHNQZXJSb3ciOnsiZGVza3RvcCI6MSwidGFibGV0IjoxLCJtb2JpbGUiOjF9fX0sImJyZWFrcG9pbnRzIjp7ImRlc2t0b3AiOnsibmFtZSI6ImRlc2t0b3AiLCJ3aWR0aCI6MTAyNH0sInRhYmxldCI6eyJuYW1lIjoidGFibGV0Iiwid2lkdGgiOjcwMH0sIm1vYmlsZSI6eyJuYW1lIjoibW9iaWxlIiwid2lkdGgiOjMwMH19fQ==\" data-wptb-adaptive-table=\"0\" data-wptb-even-row-background-color=\"#FFFFFFFF\" data-wptb-odd-row-background-color=\"#FFFFFFFF\" data-wptb-horizontal-scroll-status=\"false\" data-wptb-fixed-width-size=\"0\"><tbody><tr class=\"wptb-row\" style=\"background-color: rgb(255, 255, 255);\"><td class=\"wptb-cell\" style=\"border-width: 1px; border-style: solid; border-color: rgb(216, 216, 216); background-color: rgb(217, 237, 247);\" data-x-index=\"0\" data-y-index=\"0\" data-wptb-css-td-auto-width=\"true\" colspan=\"2\" rowspan=\"1\" data-wptb-own-bg-color=\"#D9EDF7FF\"><div class=\"wptb-text-container wptb-ph-element wptb-element-text-153\" style=\"color: rgb(74, 85, 104); font-size: 17px; padding: 0px; margin: 0px;\"><div class=\"\" style=\"position: relative;\"><p style=\"text-align: center;\"><strong>1. Materiali e requisiti del cliente<\/strong><\/p><\/div><\/div><\/td><\/tr><tr class=\"wptb-row\" data-wptb-bg-color=\"\" style=\"background-color: rgb(255, 255, 255);\"><td class=\"wptb-cell\" data-y-index=\"1\" data-x-index=\"0\" style=\"border-width: 1px; border-style: solid; border-color: rgb(216, 216, 216); background-color: rgba(0, 0, 0, 0);\" data-wptb-css-td-auto-width=\"true\" data-wptb-own-bg-color=\"#00000000\"><div class=\"wptb-text-container wptb-ph-element wptb-element-text-5\" style=\"padding: 0px; margin: 0px; color: rgb(74, 85, 104); font-size: 15px;\"><div class=\"\" style=\"position: relative;\"><p style=\"text-align: center;\" class=\"\"><strong>Materiale<\/strong><\/p><\/div><\/div><\/td><td class=\"wptb-cell\" data-y-index=\"1\" data-x-index=\"1\" style=\"border-width: 1px; background-color: rgba(234, 240, 246, 0); border-style: solid; border-color: rgb(216, 216, 216);\" data-wptb-css-td-auto-width=\"true\" data-wptb-own-bg-color=\"#EAF0F600\"><div class=\"wptb-text-container wptb-ph-element wptb-element-text-15\" style=\"padding: 0px; margin: 0px; color: rgb(74, 85, 104); font-size: 15px;\"><div class=\"\" style=\"position: relative;\"><p style=\"text-align: center;\">Composti organici agricoli<\/p><\/div><\/div><\/td><\/tr><tr class=\"wptb-row\" data-wptb-bg-color=\"\" style=\"background-color: rgb(255, 255, 255);\"><td class=\"wptb-cell\" data-y-index=\"2\" data-x-index=\"0\" style=\"border-width: 1px; border-style: solid; border-color: rgb(216, 216, 216); background-color: rgba(0, 0, 0, 0);\" data-wptb-css-td-auto-width=\"true\" data-wptb-own-bg-color=\"#00000000\"><div class=\"wptb-text-container wptb-ph-element wptb-element-text-6\" style=\"padding: 0px; margin: 0px; color: rgb(74, 85, 104); font-size: 15px;\"><div class=\"\" style=\"position: relative;\"><p style=\"text-align: center;\" class=\"\"><strong>Stato di umidit\u00e0<\/strong><\/p><\/div><\/div><\/td><td class=\"wptb-cell\" data-y-index=\"2\" data-x-index=\"1\" style=\"border-width: 1px; background-color: rgba(234, 240, 246, 0); border-style: solid; border-color: rgb(216, 216, 216);\" data-wptb-css-td-auto-width=\"true\" data-wptb-own-bg-color=\"#EAF0F600\"><div class=\"wptb-text-container wptb-ph-element wptb-element-text-41\" style=\"color: rgb(74, 85, 104); font-size: 15px; padding: 0px; margin: 0px;\"><div class=\"\" style=\"position: relative;\"><p style=\"text-align: center;\">Acqua gratis<\/p><\/div><\/div><\/td><\/tr><tr class=\"wptb-row\" data-wptb-bg-color=\"\" style=\"background-color: rgb(255, 255, 255);\"><td class=\"wptb-cell\" data-y-index=\"3\" data-x-index=\"0\" style=\"border-width: 1px; border-style: solid; border-color: rgb(216, 216, 216); background-color: rgba(0, 0, 0, 0);\" data-wptb-css-td-auto-width=\"true\" data-wptb-own-bg-color=\"#00000000\"><div class=\"wptb-text-container wptb-ph-element wptb-element-text-7\" style=\"padding: 0px; margin: 0px; color: rgb(74, 85, 104); font-size: 15px;\"><div class=\"\" style=\"position: relative;\"><p style=\"text-align: center;\" class=\"\"><strong>Evaporazione<\/strong><\/p><\/div><\/div><\/td><td class=\"wptb-cell\" data-y-index=\"3\" data-x-index=\"1\" style=\"border-width: 1px; background-color: rgba(234, 240, 246, 0); border-style: solid; border-color: rgb(216, 216, 216);\" data-wptb-css-td-auto-width=\"true\" data-wptb-own-bg-color=\"#EAF0F600\"><div class=\"wptb-text-container wptb-ph-element wptb-element-text-16\" style=\"padding: 0px; margin: 0px; color: rgb(74, 85, 104); font-size: 15px;\"><div class=\"\" style=\"position: relative;\"><p style=\"text-align: center;\">Circa 200kg\/h<\/p><\/div><\/div><\/td><\/tr><tr class=\"wptb-row\" style=\"background-color: rgb(255, 255, 255);\"><td class=\"wptb-cell\" data-y-index=\"4\" data-x-index=\"0\" style=\"border-width: 1px; border-style: solid; border-color: rgb(216, 216, 216); background-color: rgba(0, 0, 0, 0);\" data-wptb-css-td-auto-width=\"true\" data-wptb-own-bg-color=\"#00000000\"><div class=\"wptb-text-container wptb-ph-element wptb-element-text-44\" style=\"padding: 0px; margin: 0px; color: rgb(74, 85, 104); font-size: 15px;\"><div class=\"\" style=\"position: relative;\"><p style=\"text-align: center;\" class=\"\"><strong>Contenuto di umidit\u00e0 su base umida<\/strong><\/p><\/div><\/div><\/td><td class=\"wptb-cell\" data-y-index=\"4\" data-x-index=\"1\" style=\"border-width: 1px; background-color: rgba(234, 240, 246, 0); border-style: solid; border-color: rgb(216, 216, 216);\" data-wptb-css-td-auto-width=\"true\" data-wptb-own-bg-color=\"#EAF0F600\"><div class=\"wptb-text-container wptb-ph-element wptb-element-text-45\" style=\"padding: 0px; margin: 0px; color: rgb(74, 85, 104); font-size: 15px;\"><div class=\"\" style=\"position: relative;\"><p style=\"text-align: center;\">75% (acqua gratuita)<\/p><\/div><\/div><\/td><\/tr><tr class=\"wptb-row\" style=\"background-color: rgb(255, 255, 255);\"><td class=\"wptb-cell\" data-y-index=\"5\" data-x-index=\"0\" style=\"border-width: 1px; border-style: solid; border-color: rgb(216, 216, 216); background-color: rgba(0, 0, 0, 0);\" data-wptb-css-td-auto-width=\"true\" data-wptb-own-bg-color=\"#00000000\"><div class=\"wptb-text-container wptb-ph-element wptb-element-text-48\" style=\"padding: 0px; margin: 0px; color: rgb(74, 85, 104); font-size: 15px;\"><div class=\"\" style=\"position: relative;\"><p style=\"text-align: center;\" class=\"\"><strong>Contenuto di umidit\u00e0 su base secca<\/strong><\/p><\/div><\/div><\/td><td class=\"wptb-cell\" data-y-index=\"5\" data-x-index=\"1\" style=\"border-width: 1px; background-color: rgba(234, 240, 246, 0); border-style: solid; border-color: rgb(216, 216, 216);\" data-wptb-css-td-auto-width=\"true\" data-wptb-own-bg-color=\"#EAF0F600\"><div class=\"wptb-text-container wptb-ph-element wptb-element-text-49\" style=\"padding: 0px; margin: 0px; color: rgb(74, 85, 104); font-size: 15px;\"><div class=\"\" style=\"position: relative;\"><p style=\"text-align: center;\">\u22643% (acqua libera)<\/p><\/div><\/div><\/td><\/tr><tr class=\"wptb-row\" style=\"background-color: rgb(255, 255, 255);\"><td class=\"wptb-cell\" data-y-index=\"6\" data-x-index=\"0\" style=\"border-width: 1px; border-style: solid; border-color: rgb(216, 216, 216); background-color: rgba(0, 0, 0, 0);\" data-wptb-css-td-auto-width=\"true\" data-wptb-own-bg-color=\"#00000000\"><div class=\"wptb-text-container wptb-ph-element wptb-element-text-66\" style=\"padding: 0px; margin: 0px; color: rgb(74, 85, 104); font-size: 15px;\"><div class=\"\" style=\"position: relative;\"><p style=\"text-align: center;\" class=\"\"><strong>Peso specifico liquido<\/strong><\/p><\/div><\/div><\/td><td class=\"wptb-cell\" data-y-index=\"6\" data-x-index=\"1\" style=\"border-width: 1px; background-color: rgba(234, 240, 246, 0); border-style: solid; border-color: rgb(216, 216, 216);\" data-wptb-css-td-auto-width=\"true\" data-wptb-own-bg-color=\"#EAF0F600\"><div class=\"wptb-text-container wptb-ph-element wptb-element-text-67\" style=\"padding: 0px; margin: 0px; color: rgb(74, 85, 104); font-size: 15px;\"><div class=\"\" style=\"position: relative;\"><p style=\"text-align: center;\">1.2kg\/cm\u00b3<\/p><\/div><\/div><\/td><\/tr><tr class=\"wptb-row\" style=\"background-color: rgb(255, 255, 255);\"><td class=\"wptb-cell\" data-y-index=\"7\" data-x-index=\"0\" style=\"border-width: 1px; border-style: solid; border-color: rgb(216, 216, 216); background-color: rgba(0, 0, 0, 0);\" data-wptb-css-td-auto-width=\"true\" data-wptb-own-bg-color=\"#00000000\"><div class=\"wptb-text-container wptb-ph-element wptb-element-text-70\" style=\"padding: 0px; margin: 0px; color: rgb(74, 85, 104); font-size: 15px;\"><div class=\"\" style=\"position: relative;\"><p style=\"text-align: center;\"><strong>Temperatura di alimentazione<\/strong><\/p><\/div><\/div><\/td><td class=\"wptb-cell\" data-y-index=\"7\" data-x-index=\"1\" style=\"border-width: 1px; background-color: rgba(234, 240, 246, 0); border-style: solid; border-color: rgb(216, 216, 216);\" data-wptb-css-td-auto-width=\"true\" data-wptb-own-bg-color=\"#EAF0F600\"><div class=\"wptb-text-container wptb-ph-element wptb-element-text-71\" style=\"padding: 0px; margin: 0px; color: rgb(74, 85, 104); font-size: 15px;\"><div class=\"\" style=\"position: relative;\"><p style=\"text-align: center;\">10~12\u2103<\/p><\/div><\/div><\/td><\/tr><tr class=\"wptb-row\" style=\"background-color: rgb(255, 255, 255);\"><td class=\"wptb-cell\" data-y-index=\"8\" data-x-index=\"0\" style=\"border-width: 1px; border-style: solid; border-color: rgb(216, 216, 216); background-color: rgba(0, 0, 0, 0);\" data-wptb-css-td-auto-width=\"true\" data-wptb-own-bg-color=\"#00000000\"><div class=\"wptb-text-container wptb-ph-element wptb-element-text-254\" style=\"padding: 0px; margin: 0px; color: rgb(74, 85, 104); font-size: 15px;\"><div class=\"\" style=\"position: relative;\"><p style=\"text-align: center;\" class=\"\"><strong>Temperatura di scarico<\/strong><\/p><\/div><\/div><\/td><td class=\"wptb-cell\" data-y-index=\"8\" data-x-index=\"1\" style=\"border-width: 1px; background-color: rgba(234, 240, 246, 0); border-style: solid; border-color: rgb(216, 216, 216);\" data-wptb-css-td-auto-width=\"true\" data-wptb-own-bg-color=\"#EAF0F600\"><div class=\"wptb-text-container wptb-ph-element wptb-element-text-255\" style=\"padding: 0px; margin: 0px; color: rgb(74, 85, 104); font-size: 15px;\"><div class=\"\" style=\"position: relative;\"><p style=\"text-align: center;\">Circa 35\u2103<\/p><\/div><\/div><\/td><\/tr><tr class=\"wptb-row\" style=\"background-color: rgb(255, 255, 255);\"><td class=\"wptb-cell\" data-y-index=\"9\" data-x-index=\"0\" style=\"border-width: 1px; border-style: solid; border-color: rgb(216, 216, 216); background-color: rgba(0, 0, 0, 0);\" data-wptb-css-td-auto-width=\"true\" data-wptb-own-bg-color=\"#00000000\"><div class=\"wptb-text-container wptb-ph-element wptb-element-text-256\" style=\"padding: 0px; margin: 0px; color: rgb(74, 85, 104); font-size: 15px;\"><div class=\"\" style=\"position: relative;\"><p style=\"text-align: center;\"><strong>Fonte di calore<\/strong><\/p><\/div><\/div><\/td><td class=\"wptb-cell\" data-y-index=\"9\" data-x-index=\"1\" style=\"border-width: 1px; background-color: rgba(234, 240, 246, 0); border-style: solid; border-color: rgb(216, 216, 216);\" data-wptb-css-td-auto-width=\"true\" data-wptb-own-bg-color=\"#EAF0F600\"><div class=\"wptb-text-container wptb-ph-element wptb-element-text-257\" style=\"padding: 0px; margin: 0px; color: rgb(74, 85, 104); font-size: 15px;\"><div class=\"\" style=\"position: relative;\"><p style=\"text-align: center;\">Stufa ad aria calda a gas<\/p><\/div><\/div><\/td><\/tr><tr class=\"wptb-row\" style=\"background-color: rgb(255, 255, 255);\"><td class=\"wptb-cell\" data-y-index=\"10\" data-x-index=\"0\" style=\"border-width: 1px; border-style: solid; border-color: rgb(216, 216, 216); background-color: rgba(0, 0, 0, 0);\" data-wptb-css-td-auto-width=\"true\" data-wptb-own-bg-color=\"#00000000\"><div class=\"wptb-text-container wptb-ph-element wptb-element-text-258\" style=\"padding: 0px; margin: 0px; color: rgb(74, 85, 104); font-size: 15px;\"><div class=\"\" style=\"position: relative;\"><p style=\"text-align: center;\" class=\"\"><strong>Metodo di ricezione<\/strong><\/p><\/div><\/div><\/td><td class=\"wptb-cell\" data-y-index=\"10\" data-x-index=\"1\" style=\"border-width: 1px; background-color: rgba(234, 240, 246, 0); border-style: solid; border-color: rgb(216, 216, 216);\" data-wptb-css-td-auto-width=\"true\" data-wptb-own-bg-color=\"#EAF0F600\"><div class=\"wptb-text-container wptb-ph-element wptb-element-text-259\" style=\"padding: 0px; margin: 0px; color: rgb(74, 85, 104); font-size: 15px;\"><div class=\"\" style=\"position: relative;\"><p style=\"text-align: center;\">Ciclone + raccolta centralizzata di raffreddamento<\/p><\/div><\/div><\/td><\/tr><tr class=\"wptb-row\" style=\"background-color: rgb(255, 255, 255);\"><td class=\"wptb-cell\" style=\"border-width: 1px; border-style: solid; border-color: rgb(216, 216, 216); background-color: rgb(217, 237, 247);\" data-x-index=\"0\" data-y-index=\"11\" data-wptb-css-td-auto-width=\"true\" colspan=\"2\" rowspan=\"1\" data-wptb-own-bg-color=\"#D9EDF7FF\"><div class=\"wptb-text-container wptb-ph-element wptb-element-text-160\" style=\"color: rgb(74, 85, 104); font-size: 17px; padding: 0px; margin: 0px;\"><div class=\"\" style=\"position: relative;\"><p style=\"text-align: center;\" class=\"\"><strong>2. Parametri tecnici della soluzione essiccante<\/strong><\/p><\/div><\/div><\/td><\/tr><tr class=\"wptb-row\" style=\"background-color: rgb(255, 255, 255);\"><td class=\"wptb-cell\" data-y-index=\"12\" data-x-index=\"0\" style=\"border-width: 1px; border-style: solid; border-color: rgb(216, 216, 216); background-color: rgba(0, 0, 0, 0);\" data-wptb-css-td-auto-width=\"true\" data-wptb-own-bg-color=\"#00000000\"><div class=\"wptb-text-container wptb-ph-element wptb-element-text-74\" style=\"padding: 0px; margin: 0px; color: rgb(74, 85, 104); font-size: 15px;\"><div class=\"\" style=\"position: relative;\"><p style=\"text-align: center;\" class=\"\"><strong>Modello di equipaggiamento<\/strong><\/p><\/div><\/div><\/td><td class=\"wptb-cell\" data-y-index=\"12\" data-x-index=\"1\" style=\"border-width: 1px; background-color: rgba(234, 240, 246, 0); border-style: solid; border-color: rgb(216, 216, 216);\" data-wptb-css-td-auto-width=\"true\" data-wptb-own-bg-color=\"#EAF0F600\"><div class=\"wptb-text-container wptb-ph-element wptb-element-text-75\" style=\"padding: 0px; margin: 0px; color: rgb(74, 85, 104); font-size: 15px;\"><div class=\"\" style=\"position: relative;\"><p style=\"text-align: center;\">Essiccatore a spruzzo centrifugo LPG-200 *1<\/p><\/div><\/div><\/td><\/tr><tr class=\"wptb-row\" style=\"background-color: rgb(255, 255, 255);\"><td class=\"wptb-cell\" data-y-index=\"13\" data-x-index=\"0\" style=\"border-width: 1px; border-style: solid; border-color: rgb(216, 216, 216); background-color: rgba(0, 0, 0, 0);\" data-wptb-css-td-auto-width=\"true\" data-wptb-own-bg-color=\"#00000000\"><div class=\"wptb-text-container wptb-ph-element wptb-element-text-78\" style=\"padding: 0px; margin: 0px; color: rgb(74, 85, 104); font-size: 15px;\"><div class=\"\" style=\"position: relative;\"><p style=\"text-align: center;\"><strong>Metodo di atomizzazione<\/strong><\/p><\/div><\/div><\/td><td class=\"wptb-cell\" data-y-index=\"13\" data-x-index=\"1\" style=\"border-width: 1px; background-color: rgba(234, 240, 246, 0); border-style: solid; border-color: rgb(216, 216, 216);\" data-wptb-css-td-auto-width=\"true\" data-wptb-own-bg-color=\"#EAF0F600\"><div class=\"wptb-text-container wptb-ph-element wptb-element-text-79\" style=\"padding: 0px; margin: 0px; color: rgb(74, 85, 104); font-size: 15px;\"><div class=\"\" style=\"position: relative;\"><p style=\"text-align: center;\">Centrifugo<\/p><\/div><\/div><\/td><\/tr><tr class=\"wptb-row\" style=\"background-color: rgb(255, 255, 255);\"><td class=\"wptb-cell\" data-y-index=\"14\" data-x-index=\"0\" style=\"border-width: 1px; border-style: solid; border-color: rgb(216, 216, 216); background-color: rgba(0, 0, 0, 0);\" data-wptb-css-td-auto-width=\"true\" data-wptb-own-bg-color=\"#00000000\"><div class=\"wptb-text-container wptb-ph-element wptb-element-text-82\" style=\"padding: 0px; margin: 0px; color: rgb(74, 85, 104); font-size: 15px;\"><div class=\"\" style=\"position: relative;\"><p style=\"text-align: center;\" class=\"\"><strong>Metodo di contatto con aria calda<\/strong><\/p><\/div><\/div><\/td><td class=\"wptb-cell\" data-y-index=\"14\" data-x-index=\"1\" style=\"border-width: 1px; background-color: rgba(234, 240, 246, 0); border-style: solid; border-color: rgb(216, 216, 216);\" data-wptb-css-td-auto-width=\"true\" data-wptb-own-bg-color=\"#EAF0F600\"><div class=\"wptb-text-container wptb-ph-element wptb-element-text-83\" style=\"padding: 0px; margin: 0px; color: rgb(74, 85, 104); font-size: 15px;\"><div class=\"\" style=\"position: relative;\"><p style=\"text-align: center;\">Flusso parallelo<\/p><\/div><\/div><\/td><\/tr><tr class=\"wptb-row\" style=\"background-color: rgb(255, 255, 255);\"><td class=\"wptb-cell\" data-y-index=\"15\" data-x-index=\"0\" style=\"border-width: 1px; border-style: solid; border-color: rgb(216, 216, 216); background-color: rgba(0, 0, 0, 0);\" data-wptb-css-td-auto-width=\"true\" data-wptb-own-bg-color=\"#00000000\"><div class=\"wptb-text-container wptb-ph-element wptb-element-text-86\" style=\"padding: 0px; margin: 0px; color: rgb(74, 85, 104); font-size: 15px;\"><div class=\"\" style=\"position: relative;\"><p style=\"text-align: center;\" class=\"\"><strong>Temperatura dell'aria in ingresso<\/strong><\/p><\/div><\/div><\/td><td class=\"wptb-cell\" data-y-index=\"15\" data-x-index=\"1\" style=\"border-width: 1px; background-color: rgba(234, 240, 246, 0); border-style: solid; border-color: rgb(216, 216, 216);\" data-wptb-css-td-auto-width=\"true\" data-wptb-own-bg-color=\"#EAF0F600\"><div class=\"wptb-text-container wptb-ph-element wptb-element-text-87\" style=\"padding: 0px; margin: 0px; color: rgb(74, 85, 104); font-size: 15px;\"><div class=\"\" style=\"position: relative;\"><p style=\"text-align: center;\">160~220\u2103<\/p><\/div><\/div><\/td><\/tr><tr class=\"wptb-row\" style=\"background-color: rgb(255, 255, 255);\"><td class=\"wptb-cell\" data-y-index=\"16\" data-x-index=\"0\" style=\"border-width: 1px; border-style: solid; border-color: rgb(216, 216, 216); background-color: rgba(0, 0, 0, 0);\" data-wptb-css-td-auto-width=\"true\" data-wptb-own-bg-color=\"#00000000\"><div class=\"wptb-text-container wptb-ph-element wptb-element-text-90\" style=\"padding: 0px; margin: 0px; color: rgb(74, 85, 104); font-size: 15px;\"><div class=\"\" style=\"position: relative;\"><p style=\"text-align: center;\" class=\"\"><strong>Temperatura dell'aria in uscita<\/strong><\/p><\/div><\/div><\/td><td class=\"wptb-cell\" data-y-index=\"16\" data-x-index=\"1\" style=\"border-width: 1px; background-color: rgba(234, 240, 246, 0); border-style: solid; border-color: rgb(216, 216, 216);\" data-wptb-css-td-auto-width=\"true\" data-wptb-own-bg-color=\"#EAF0F600\"><div class=\"wptb-text-container wptb-ph-element wptb-element-text-91\" style=\"padding: 0px; margin: 0px; color: rgb(74, 85, 104); font-size: 15px;\"><div class=\"\" style=\"position: relative;\"><p style=\"text-align: center;\">80~100\u2103<\/p><\/div><\/div><\/td><\/tr><tr class=\"wptb-row\" style=\"background-color: rgb(255, 255, 255);\"><td class=\"wptb-cell\" data-y-index=\"17\" data-x-index=\"0\" style=\"border-width: 1px; border-style: solid; border-color: rgb(216, 216, 216); background-color: rgba(0, 0, 0, 0);\" data-wptb-css-td-auto-width=\"true\" data-wptb-own-bg-color=\"#00000000\"><div class=\"wptb-text-container wptb-ph-element wptb-element-text-94\" style=\"padding: 0px; margin: 0px; color: rgb(74, 85, 104); font-size: 15px;\"><div class=\"\" style=\"position: relative;\"><p style=\"text-align: center;\"><strong>Requisiti materiali<\/strong><\/p><\/div><\/div><\/td><td class=\"wptb-cell\" data-y-index=\"17\" data-x-index=\"1\" style=\"border-width: 1px; background-color: rgba(234, 240, 246, 0); border-style: solid; border-color: rgb(216, 216, 216);\" data-wptb-css-td-auto-width=\"true\" data-wptb-own-bg-color=\"#EAF0F600\"><div class=\"wptb-text-container wptb-ph-element wptb-element-text-95\" style=\"padding: 0px; margin: 0px; color: rgb(74, 85, 104); font-size: 15px;\"><div class=\"\" style=\"position: relative;\"><p style=\"text-align: center;\">Contatto del prodotto SUS304<\/p><\/div><\/div><\/td><\/tr><tr class=\"wptb-row\" style=\"background-color: rgb(255, 255, 255);\"><td class=\"wptb-cell\" data-y-index=\"18\" data-x-index=\"0\" style=\"border-width: 1px; border-style: solid; border-color: rgb(216, 216, 216); background-color: rgba(0, 0, 0, 0);\" data-wptb-css-td-auto-width=\"true\" data-wptb-own-bg-color=\"#00000000\"><div class=\"wptb-text-container wptb-ph-element wptb-element-text-98\" style=\"padding: 0px; margin: 0px; color: rgb(74, 85, 104); font-size: 15px;\"><div class=\"\" style=\"position: relative;\"><p style=\"text-align: center;\" class=\"\"><strong>Metodo di rimozione della polvere<\/strong><\/p><\/div><\/div><\/td><td class=\"wptb-cell\" data-y-index=\"18\" data-x-index=\"1\" style=\"border-width: 1px; background-color: rgba(234, 240, 246, 0); border-style: solid; border-color: rgb(216, 216, 216);\" data-wptb-css-td-auto-width=\"true\" data-wptb-own-bg-color=\"#EAF0F600\"><div class=\"wptb-text-container wptb-ph-element wptb-element-text-99\" style=\"padding: 0px; margin: 0px; color: rgb(74, 85, 104); font-size: 15px;\"><div class=\"\" style=\"position: relative;\"><p style=\"text-align: center;\">Separatore a ciclone<\/p><\/div><\/div><\/td><\/tr><tr class=\"wptb-row\" style=\"background-color: rgb(255, 255, 255);\"><td class=\"wptb-cell\" data-y-index=\"19\" data-x-index=\"0\" style=\"border-width: 1px; border-style: solid; border-color: rgb(216, 216, 216); background-color: rgba(0, 0, 0, 0);\" data-wptb-css-td-auto-width=\"true\" data-wptb-own-bg-color=\"#00000000\"><div class=\"wptb-text-container wptb-ph-element wptb-element-text-102\" style=\"padding: 0px; margin: 0px; color: rgb(74, 85, 104); font-size: 15px;\"><div class=\"\" style=\"position: relative;\"><p style=\"text-align: center;\" class=\"\"><strong>Metodo di riscaldamento<\/strong><\/p><\/div><\/div><\/td><td class=\"wptb-cell\" data-y-index=\"19\" data-x-index=\"1\" style=\"border-width: 1px; background-color: rgba(234, 240, 246, 0); border-style: solid; border-color: rgb(216, 216, 216);\" data-wptb-css-td-auto-width=\"true\" data-wptb-own-bg-color=\"#EAF0F600\"><div class=\"wptb-text-container wptb-ph-element wptb-element-text-103\" style=\"padding: 0px; margin: 0px; color: rgb(74, 85, 104); font-size: 15px;\"><div class=\"\" style=\"position: relative;\"><p style=\"text-align: center;\">Stufa ad aria calda a gas<\/p><\/div><\/div><\/td><\/tr><tr class=\"wptb-row\" style=\"background-color: rgb(255, 255, 255);\"><td class=\"wptb-cell\" data-y-index=\"20\" data-x-index=\"0\" style=\"border-width: 1px; border-style: solid; border-color: rgb(216, 216, 216); background-color: rgba(0, 0, 0, 0);\" data-wptb-css-td-auto-width=\"true\" data-wptb-own-bg-color=\"#00000000\"><div class=\"wptb-text-container wptb-ph-element wptb-element-text-106\" style=\"padding: 0px; margin: 0px; color: rgb(74, 85, 104); font-size: 15px;\"><div class=\"\" style=\"position: relative;\"><p style=\"text-align: center;\" class=\"\"><strong>Metodo di alimentazione<\/strong><\/p><\/div><\/div><\/td><td class=\"wptb-cell\" data-y-index=\"20\" data-x-index=\"1\" style=\"border-width: 1px; background-color: rgba(234, 240, 246, 0); border-style: solid; border-color: rgb(216, 216, 216);\" data-wptb-css-td-auto-width=\"true\" data-wptb-own-bg-color=\"#EAF0F600\"><div class=\"wptb-text-container wptb-ph-element wptb-element-text-107\" style=\"padding: 0px; margin: 0px; color: rgb(74, 85, 104); font-size: 15px;\"><div class=\"\" style=\"position: relative;\"><p style=\"text-align: center;\">Alimentazione con pompa a coclea<\/p><\/div><\/div><\/td><\/tr><tr class=\"wptb-row\" style=\"background-color: rgb(255, 255, 255);\"><td class=\"wptb-cell\" data-y-index=\"21\" data-x-index=\"0\" style=\"border-width: 1px; border-style: solid; border-color: rgb(216, 216, 216); background-color: rgba(0, 0, 0, 0);\" data-wptb-css-td-auto-width=\"true\" data-wptb-own-bg-color=\"#00000000\"><div class=\"wptb-text-container wptb-ph-element wptb-element-text-110\" style=\"padding: 0px; margin: 0px; color: rgb(74, 85, 104); font-size: 15px;\"><div class=\"\" style=\"position: relative;\"><p style=\"text-align: center;\" class=\"\"><strong>Sito di installazione<\/strong><\/p><\/div><\/div><\/td><td class=\"wptb-cell\" data-y-index=\"21\" data-x-index=\"1\" style=\"border-width: 1px; background-color: rgba(234, 240, 246, 0); border-style: solid; border-color: rgb(216, 216, 216);\" data-wptb-css-td-auto-width=\"true\" data-wptb-own-bg-color=\"#EAF0F600\"><div class=\"wptb-text-container wptb-ph-element wptb-element-text-111\" style=\"padding: 0px; margin: 0px; color: rgb(74, 85, 104); font-size: 15px;\"><div class=\"\" style=\"position: relative;\"><p style=\"text-align: center;\">Area generale per la torre principale, area pulita per il ricevimento dei materiali<\/p><\/div><grammarly-extension data-grammarly-shadow-root=\"true\" style=\"position: absolute; top: -1px; left: -1px; pointer-events: none; z-index: auto;\" class=\"cGcvT\"><\/grammarly-extension><grammarly-extension data-grammarly-shadow-root=\"true\" style=\"mix-blend-mode: darken; position: absolute; top: -1px; left: -1px; pointer-events: none; z-index: auto;\" class=\"cGcvT\"><\/grammarly-extension><grammarly-extension data-grammarly-shadow-root=\"true\" style=\"position: absolute; top: -1px; left: -1px; pointer-events: none; z-index: auto;\" class=\"cGcvT\"><\/grammarly-extension><grammarly-extension data-grammarly-shadow-root=\"true\" style=\"mix-blend-mode: darken; position: absolute; top: -1px; left: -1px; pointer-events: none; z-index: auto;\" class=\"cGcvT\"><\/grammarly-extension><\/div><\/td><\/tr><tr class=\"wptb-row\" style=\"background-color: rgb(255, 255, 255);\"><td class=\"wptb-cell\" data-y-index=\"22\" data-x-index=\"0\" style=\"border-width: 1px; border-style: solid; border-color: rgb(216, 216, 216); background-color: rgba(0, 0, 0, 0);\" data-wptb-css-td-auto-width=\"true\" data-wptb-own-bg-color=\"#00000000\"><div class=\"wptb-text-container wptb-ph-element wptb-element-text-260\" style=\"padding: 0px; margin: 0px; color: rgb(74, 85, 104); font-size: 15px;\"><div class=\"\" style=\"position: relative;\"><p style=\"text-align: center;\" class=\"\"><strong>Dimensioni del sito di installazione<\/strong><\/p><\/div><\/div><\/td><td class=\"wptb-cell\" data-y-index=\"22\" data-x-index=\"1\" style=\"border-width: 1px; background-color: rgba(234, 240, 246, 0); border-style: solid; border-color: rgb(216, 216, 216);\" data-wptb-css-td-auto-width=\"true\" data-wptb-own-bg-color=\"#EAF0F600\"><div class=\"wptb-text-container wptb-ph-element wptb-element-text-261\" style=\"padding: 0px; margin: 0px; color: rgb(74, 85, 104); font-size: 15px;\"><div class=\"\" style=\"position: relative;\"><p style=\"text-align: center;\">\u00c8 richiesto il disegno delle condizioni dell'impianto<\/p><\/div><grammarly-extension data-grammarly-shadow-root=\"true\" style=\"position: absolute; top: -1px; left: -1px; pointer-events: none; z-index: auto;\" class=\"cGcvT\"><\/grammarly-extension><grammarly-extension data-grammarly-shadow-root=\"true\" style=\"mix-blend-mode: darken; position: absolute; top: -1px; left: -1px; pointer-events: none; z-index: auto;\" class=\"cGcvT\"><\/grammarly-extension><\/div><\/td><\/tr><tr class=\"wptb-row\" style=\"background-color: rgb(255, 255, 255);\"><td class=\"wptb-cell\" data-y-index=\"23\" data-x-index=\"0\" style=\"border-width: 1px; border-style: solid; border-color: rgb(216, 216, 216); background-color: rgba(0, 0, 0, 0);\" data-wptb-css-td-auto-width=\"true\" data-wptb-own-bg-color=\"#00000000\"><div class=\"wptb-text-container wptb-ph-element wptb-element-text-262\" style=\"padding: 0px; margin: 0px; color: rgb(74, 85, 104); font-size: 15px;\"><div class=\"\" style=\"position: relative;\"><p style=\"text-align: center;\"><strong>Rumore<\/strong><\/p><\/div><\/div><\/td><td class=\"wptb-cell\" data-y-index=\"23\" data-x-index=\"1\" style=\"border-width: 1px; background-color: rgba(234, 240, 246, 0); border-style: solid; border-color: rgb(216, 216, 216);\" data-wptb-css-td-auto-width=\"true\" data-wptb-own-bg-color=\"#EAF0F600\"><div class=\"wptb-text-container wptb-ph-element wptb-element-text-263\" style=\"padding: 0px; margin: 0px; color: rgb(74, 85, 104); font-size: 15px;\"><div class=\"\" style=\"position: relative;\"><p style=\"text-align: center;\">\uff1c80 dB<\/p><\/div><grammarly-extension data-grammarly-shadow-root=\"true\" style=\"position: absolute; top: -1px; left: -1px; pointer-events: none; z-index: auto;\" class=\"cGcvT\"><\/grammarly-extension><grammarly-extension data-grammarly-shadow-root=\"true\" style=\"mix-blend-mode: darken; position: absolute; top: -1px; left: -1px; pointer-events: none; z-index: auto;\" class=\"cGcvT\"><\/grammarly-extension><\/div><\/td><\/tr><tr class=\"wptb-row\" style=\"background-color: rgb(255, 255, 255);\"><td class=\"wptb-cell\" style=\"border-width: 1px; border-style: solid; border-color: rgb(216, 216, 216); background-color: rgb(217, 237, 247);\" data-x-index=\"0\" data-y-index=\"24\" data-wptb-css-td-auto-width=\"true\" colspan=\"2\" rowspan=\"1\" data-wptb-own-bg-color=\"#D9EDF7FF\"><div class=\"wptb-text-container wptb-ph-element wptb-element-text-166\" style=\"color: rgb(74, 85, 104); font-size: 17px; padding: 0px; margin: 0px;\"><div class=\"\" style=\"position: relative;\"><p style=\"text-align: center;\"><strong>3. Condizioni dei lavori pubblici<\/strong><\/p><\/div><\/div><\/td><\/tr><tr class=\"wptb-row\" style=\"background-color: rgb(255, 255, 255);\"><td class=\"wptb-cell\" data-y-index=\"25\" data-x-index=\"0\" style=\"border-width: 1px; border-style: solid; border-color: rgb(216, 216, 216); background-color: rgba(0, 0, 0, 0);\" data-wptb-css-td-auto-width=\"true\" data-wptb-own-bg-color=\"#00000000\"><div class=\"wptb-text-container wptb-ph-element wptb-element-text-182\" style=\"padding: 0px; margin: 0px; color: rgb(74, 85, 104); font-size: 15px;\"><div class=\"\" style=\"position: relative;\"><p style=\"text-align: center;\" class=\"\"><strong>Pressione atmosferica<\/strong><\/p><\/div><\/div><\/td><td class=\"wptb-cell\" data-y-index=\"25\" data-x-index=\"1\" style=\"border-width: 1px; background-color: rgba(234, 240, 246, 0); border-style: solid; border-color: rgb(216, 216, 216);\" data-wptb-css-td-auto-width=\"true\" data-wptb-own-bg-color=\"#EAF0F600\"><div class=\"wptb-text-container wptb-ph-element wptb-element-text-183\" style=\"padding: 0px; margin: 0px; color: rgb(74, 85, 104); font-size: 15px;\"><div class=\"\" style=\"position: relative;\"><p style=\"text-align: center;\">101.3KPa<\/p><\/div><\/div><\/td><\/tr><tr class=\"wptb-row\" style=\"background-color: rgb(255, 255, 255);\"><td class=\"wptb-cell\" data-y-index=\"26\" data-x-index=\"0\" style=\"border-width: 1px; border-style: solid; border-color: rgb(216, 216, 216); background-color: rgba(0, 0, 0, 0);\" data-wptb-css-td-auto-width=\"true\" data-wptb-own-bg-color=\"#00000000\"><div class=\"wptb-text-container wptb-ph-element wptb-element-text-202\" style=\"padding: 0px; margin: 0px; color: rgb(74, 85, 104); font-size: 15px;\"><div class=\"\" style=\"position: relative;\"><p style=\"text-align: center;\" class=\"\"><strong>Temperatura ambiente<\/strong><\/p><\/div><\/div><\/td><td class=\"wptb-cell\" data-y-index=\"26\" data-x-index=\"1\" style=\"border-width: 1px; background-color: rgba(234, 240, 246, 0); border-style: solid; border-color: rgb(216, 216, 216);\" data-wptb-css-td-auto-width=\"true\" data-wptb-own-bg-color=\"#EAF0F600\"><div class=\"wptb-text-container wptb-ph-element wptb-element-text-203\" style=\"padding: 0px; margin: 0px; color: rgb(74, 85, 104); font-size: 15px;\"><div class=\"\" style=\"position: relative;\"><p style=\"text-align: center;\">10\u2103<\/p><\/div><\/div><\/td><\/tr><tr class=\"wptb-row\" style=\"background-color: rgb(255, 255, 255);\"><td class=\"wptb-cell\" data-y-index=\"27\" data-x-index=\"0\" style=\"border-width: 1px; border-style: solid; border-color: rgb(216, 216, 216); background-color: rgba(0, 0, 0, 0);\" data-wptb-css-td-auto-width=\"true\" data-wptb-own-bg-color=\"#00000000\"><div class=\"wptb-text-container wptb-ph-element wptb-element-text-197\" style=\"padding: 0px; margin: 0px; color: rgb(74, 85, 104); font-size: 15px;\"><div class=\"\" style=\"position: relative;\"><p style=\"text-align: center;\" class=\"\"><strong>Umidit\u00e0 relativa<\/strong><\/p><\/div><\/div><\/td><td class=\"wptb-cell\" data-y-index=\"27\" data-x-index=\"1\" style=\"border-width: 1px; background-color: rgba(234, 240, 246, 0); border-style: solid; border-color: rgb(216, 216, 216);\" data-wptb-css-td-auto-width=\"true\" data-wptb-own-bg-color=\"#EAF0F600\"><div class=\"wptb-text-container wptb-ph-element wptb-element-text-198\" style=\"padding: 0px; margin: 0px; color: rgb(74, 85, 104); font-size: 15px;\"><div class=\"\" style=\"position: relative;\"><p style=\"text-align: center;\">70%<\/p><\/div><\/div><\/td><\/tr><tr class=\"wptb-row\" style=\"background-color: rgb(255, 255, 255);\"><td class=\"wptb-cell\" data-y-index=\"28\" data-x-index=\"0\" style=\"border-width: 1px; border-style: solid; border-color: rgb(216, 216, 216); background-color: rgba(0, 0, 0, 0);\" data-wptb-css-td-auto-width=\"true\" data-wptb-own-bg-color=\"#00000000\"><div class=\"wptb-text-container wptb-ph-element wptb-element-text-192\" style=\"padding: 0px; margin: 0px; color: rgb(74, 85, 104); font-size: 15px;\"><div class=\"\" style=\"position: relative;\"><p style=\"text-align: center;\" class=\"\"><strong>Energia elettrica<\/strong><\/p><\/div><\/div><\/td><td class=\"wptb-cell\" data-y-index=\"28\" data-x-index=\"1\" style=\"border-width: 1px; background-color: rgba(234, 240, 246, 0); border-style: solid; border-color: rgb(216, 216, 216);\" data-wptb-css-td-auto-width=\"true\" data-wptb-own-bg-color=\"#EAF0F600\"><div class=\"wptb-text-container wptb-ph-element wptb-element-text-193\" style=\"padding: 0px; margin: 0px; color: rgb(74, 85, 104); font-size: 15px;\"><div class=\"\" style=\"position: relative;\"><p style=\"text-align: center;\">380V, trifase, 50Hz<\/p><\/div><\/div><\/td><\/tr><tr class=\"wptb-row\" style=\"background-color: rgb(255, 255, 255);\"><td class=\"wptb-cell\" data-y-index=\"29\" data-x-index=\"0\" style=\"border-width: 1px; border-style: solid; border-color: rgb(216, 216, 216); background-color: rgba(0, 0, 0, 0);\" data-wptb-css-td-auto-width=\"true\" data-wptb-own-bg-color=\"#00000000\"><div class=\"wptb-text-container wptb-ph-element wptb-element-text-207\" style=\"padding: 0px; margin: 0px; color: rgb(74, 85, 104); font-size: 15px;\"><div class=\"\" style=\"position: relative;\"><p style=\"text-align: center;\"><strong>Potenza della macchina<\/strong><\/p><\/div><\/div><\/td><td class=\"wptb-cell\" data-y-index=\"29\" data-x-index=\"1\" style=\"border-width: 1px; background-color: rgba(234, 240, 246, 0); border-style: solid; border-color: rgb(216, 216, 216);\" data-wptb-css-td-auto-width=\"true\" data-wptb-own-bg-color=\"#EAF0F600\"><div class=\"wptb-text-container wptb-ph-element wptb-element-text-208\" style=\"padding: 0px; margin: 0px; color: rgb(74, 85, 104); font-size: 15px;\"><div class=\"\" style=\"position: relative;\"><p style=\"text-align: center;\">Circa 50 KW<\/p><\/div><\/div><\/td><\/tr><tr class=\"wptb-row\" style=\"background-color: rgb(255, 255, 255);\"><td class=\"wptb-cell\" data-y-index=\"30\" data-x-index=\"0\" style=\"border-width: 1px; border-style: solid; border-color: rgb(216, 216, 216); background-color: rgba(0, 0, 0, 0);\" data-wptb-css-td-auto-width=\"true\" data-wptb-own-bg-color=\"#00000000\"><div class=\"wptb-text-container wptb-ph-element wptb-element-text-212\" style=\"padding: 0px; margin: 0px; color: rgb(74, 85, 104); font-size: 15px;\"><div class=\"\" style=\"position: relative;\"><p style=\"text-align: center;\"><strong>Consumo di aria compressa<\/strong><\/p><\/div><\/div><\/td><td class=\"wptb-cell\" data-y-index=\"30\" data-x-index=\"1\" style=\"border-width: 1px; background-color: rgba(234, 240, 246, 0); border-style: solid; border-color: rgb(216, 216, 216);\" data-wptb-css-td-auto-width=\"true\" data-wptb-own-bg-color=\"#EAF0F600\"><div class=\"wptb-text-container wptb-ph-element wptb-element-text-213\" style=\"padding: 0px; margin: 0px; color: rgb(74, 85, 104); font-size: 15px;\"><div class=\"\" style=\"position: relative;\"><p style=\"text-align: center;\">0.8m\u00b3\/min<\/p><\/div><\/div><\/td><\/tr><tr class=\"wptb-row\" style=\"background-color: rgb(255, 255, 255);\"><td class=\"wptb-cell\" data-y-index=\"31\" data-x-index=\"0\" style=\"border-width: 1px; border-style: solid; border-color: rgb(216, 216, 216); background-color: rgba(0, 0, 0, 0);\" data-wptb-css-td-auto-width=\"true\" data-wptb-own-bg-color=\"#00000000\"><div class=\"wptb-text-container wptb-ph-element wptb-element-text-217\" style=\"padding: 0px; margin: 0px; color: rgb(74, 85, 104); font-size: 15px;\"><div class=\"\" style=\"position: relative;\"><p style=\"text-align: center;\"><strong>Consumo di gas naturale<\/strong><\/p><\/div><\/div><\/td><td class=\"wptb-cell\" data-y-index=\"31\" data-x-index=\"1\" style=\"border-width: 1px; background-color: rgba(234, 240, 246, 0); border-style: solid; border-color: rgb(216, 216, 216);\" data-wptb-css-td-auto-width=\"true\" data-wptb-own-bg-color=\"#EAF0F600\"><div class=\"wptb-text-container wptb-ph-element wptb-element-text-218\" style=\"padding: 0px; margin: 0px; color: rgb(74, 85, 104); font-size: 15px;\"><div class=\"\" style=\"position: relative;\"><p style=\"text-align: center;\">42Nm\u00b3 \/h<\/p><\/div><\/div><\/td><\/tr><tr class=\"wptb-row\" style=\"background-color: rgb(255, 255, 255);\"><td class=\"wptb-cell\" data-y-index=\"32\" data-x-index=\"0\" style=\"border-width: 1px; border-style: solid; border-color: rgb(216, 216, 216); background-color: rgba(0, 0, 0, 0);\" data-wptb-css-td-auto-width=\"true\" data-wptb-own-bg-color=\"#00000000\"><div class=\"wptb-text-container wptb-ph-element wptb-element-text-222\" style=\"padding: 0px; margin: 0px; color: rgb(74, 85, 104); font-size: 15px;\"><div class=\"\" style=\"position: relative;\"><p style=\"text-align: center;\"><strong>Pressione dell'aria compressa<\/strong><\/p><\/div><\/div><\/td><td class=\"wptb-cell\" data-y-index=\"32\" data-x-index=\"1\" style=\"border-width: 1px; background-color: rgba(234, 240, 246, 0); border-style: solid; border-color: rgb(216, 216, 216);\" data-wptb-css-td-auto-width=\"true\" data-wptb-own-bg-color=\"#EAF0F600\"><div class=\"wptb-text-container wptb-ph-element wptb-element-text-223\" style=\"padding: 0px; margin: 0px; color: rgb(74, 85, 104); font-size: 15px;\"><div class=\"\" style=\"position: relative;\"><p style=\"text-align: center;\">0.3~0.6mpa<\/p><\/div><\/div><\/td><\/tr><\/tbody><\/table>\n<\/div>\n\n<p><strong>2. La nostra soluzione essiccante per essiccatore a spruzzo centrifugo LPG-2000 per succo di mango<\/strong><\/p>\n<div class=\"wptb-container-legacy\" data-table-id=\"9289\">\n    <table class=\"wptb-preview-table wptb-element-main-table_setting-2909 edit-active\" data-reconstraction=\"0\" style=\"border: 1px solid rgb(216, 216, 216); display: table;\" data-wptb-table-tds-sum-max-width=\"263.5\" data-wptb-cells-width-auto-count=\"2\" role=\"table\" data-wptb-header-background-color=\"#ffffff\" data-table-columns=\"2\" data-wptb-table-directives=\"eyJpbm5lckJvcmRlcnMiOnsiYWN0aXZlIjoiYWxsIiwiYm9yZGVyV2lkdGgiOiIxIiwiYm9yZGVyUmFkaXVzZXMiOnsiYWxsIjpudWxsfX19\" data-wptb-extra-styles=\"LndwdGItcmliYm9uX2VsZW1lbnQtY29udGFpbmVyIHsKICB0b3A6IC03JTsKfQogIA==\" data-wptb-responsive-directives=\"eyJyZXNwb25zaXZlRW5hYmxlZCI6dHJ1ZSwicmVzcG9uc2l2ZU1vZGUiOiJhdXRvIiwicHJlc2VydmVSb3dDb2xvciI6ZmFsc2UsInJlbGF0aXZlV2lkdGgiOiJ3aW5kb3ciLCJoZWFkZXJGdWxseU1lcmdlZCI6ZmFsc2UsIm1vZGVPcHRpb25zIjp7ImF1dG8iOnsiZGlzYWJsZWQiOnsiZGVza3RvcCI6ZmFsc2UsInRhYmxldCI6ZmFsc2UsIm1vYmlsZSI6ZmFsc2V9LCJ0b3BSb3dBc0hlYWRlciI6eyJkZXNrdG9wIjpmYWxzZSwidGFibGV0Ijp0cnVlLCJtb2JpbGUiOmZhbHNlfSwicmVwZWF0TWVyZ2VkSGVhZGVyIjp7ImRlc2t0b3AiOnRydWUsInRhYmxldCI6dHJ1ZSwibW9iaWxlIjp0cnVlfSwic3RhdGljVG9wUm93Ijp7ImRlc2t0b3AiOmZhbHNlLCJ0YWJsZXQiOmZhbHNlLCJtb2JpbGUiOmZhbHNlfSwiY2VsbFN0YWNrRGlyZWN0aW9uIjp7ImRlc2t0b3AiOiJyb3ciLCJ0YWJsZXQiOiJyb3ciLCJtb2JpbGUiOiJjb2x1bW4ifSwiY2VsbHNQZXJSb3ciOnsiZGVza3RvcCI6MSwidGFibGV0IjoxLCJtb2JpbGUiOjF9fX0sImJyZWFrcG9pbnRzIjp7ImRlc2t0b3AiOnsibmFtZSI6ImRlc2t0b3AiLCJ3aWR0aCI6MTAyNH0sInRhYmxldCI6eyJuYW1lIjoidGFibGV0Iiwid2lkdGgiOjcwMH0sIm1vYmlsZSI6eyJuYW1lIjoibW9iaWxlIiwid2lkdGgiOjMwMH19fQ==\" data-wptb-adaptive-table=\"0\" data-wptb-even-row-background-color=\"#FFFFFFFF\" data-wptb-odd-row-background-color=\"#FFFFFFFF\" data-wptb-horizontal-scroll-status=\"false\" data-wptb-fixed-width-size=\"0\"><tbody><tr class=\"wptb-row\" style=\"background-color: rgb(255, 255, 255);\"><td class=\"wptb-cell\" style=\"border-width: 1px; border-style: solid; border-color: rgb(216, 216, 216); background-color: rgb(217, 237, 247);\" data-x-index=\"0\" data-y-index=\"0\" data-wptb-css-td-auto-width=\"true\" colspan=\"2\" rowspan=\"1\" data-wptb-own-bg-color=\"#D9EDF7FF\"><div class=\"wptb-text-container wptb-ph-element wptb-element-text-153\" style=\"color: rgb(74, 85, 104); font-size: 17px; padding: 0px; margin: 0px;\"><div class=\"\" style=\"position: relative;\"><p style=\"text-align: center;\" class=\"\"><strong>1. Materiali e requisiti del cliente<\/strong><\/p><\/div><\/div><\/td><\/tr><tr class=\"wptb-row\" data-wptb-bg-color=\"\" style=\"background-color: rgb(255, 255, 255);\"><td class=\"wptb-cell\" data-y-index=\"1\" data-x-index=\"0\" style=\"border-width: 1px; border-style: solid; border-color: rgb(216, 216, 216); background-color: rgba(0, 0, 0, 0);\" data-wptb-css-td-auto-width=\"true\" data-wptb-own-bg-color=\"#00000000\"><div class=\"wptb-text-container wptb-ph-element wptb-element-text-5\" style=\"padding: 0px; margin: 0px; color: rgb(74, 85, 104); font-size: 15px;\"><div class=\"\" style=\"position: relative;\"><p style=\"text-align: center;\"><strong>Materiale<\/strong><\/p><\/div><\/div><\/td><td class=\"wptb-cell\" data-y-index=\"1\" data-x-index=\"1\" style=\"border-width: 1px; background-color: rgba(234, 240, 246, 0); border-style: solid; border-color: rgb(216, 216, 216);\" data-wptb-css-td-auto-width=\"true\" data-wptb-own-bg-color=\"#EAF0F600\"><div class=\"wptb-text-container wptb-ph-element wptb-element-text-15\" style=\"padding: 0px; margin: 0px; color: rgb(74, 85, 104); font-size: 15px;\"><div class=\"\" style=\"position: relative;\"><p style=\"text-align: center;\">Succo di mango<\/p><\/div><\/div><\/td><\/tr><tr class=\"wptb-row\" data-wptb-bg-color=\"\" style=\"background-color: rgb(255, 255, 255);\"><td class=\"wptb-cell\" data-y-index=\"2\" data-x-index=\"0\" style=\"border-width: 1px; border-style: solid; border-color: rgb(216, 216, 216); background-color: rgba(0, 0, 0, 0);\" data-wptb-css-td-auto-width=\"true\" data-wptb-own-bg-color=\"#00000000\"><div class=\"wptb-text-container wptb-ph-element wptb-element-text-6\" style=\"padding: 0px; margin: 0px; color: rgb(74, 85, 104); font-size: 15px;\"><div class=\"\" style=\"position: relative;\"><p style=\"text-align: center;\" class=\"\"><strong>Stato di umidit\u00e0<\/strong><\/p><\/div><\/div><\/td><td class=\"wptb-cell\" data-y-index=\"2\" data-x-index=\"1\" style=\"border-width: 1px; background-color: rgba(234, 240, 246, 0); border-style: solid; border-color: rgb(216, 216, 216);\" data-wptb-css-td-auto-width=\"true\" data-wptb-own-bg-color=\"#EAF0F600\"><div class=\"wptb-text-container wptb-ph-element wptb-element-text-41\" style=\"color: rgb(74, 85, 104); font-size: 15px; padding: 0px; margin: 0px;\"><div class=\"\" style=\"position: relative;\"><p style=\"text-align: center;\">Acqua gratis<\/p><\/div><\/div><\/td><\/tr><tr class=\"wptb-row\" data-wptb-bg-color=\"\" style=\"background-color: rgb(255, 255, 255);\"><td class=\"wptb-cell\" data-y-index=\"3\" data-x-index=\"0\" style=\"border-width: 1px; border-style: solid; border-color: rgb(216, 216, 216); background-color: rgba(0, 0, 0, 0);\" data-wptb-css-td-auto-width=\"true\" data-wptb-own-bg-color=\"#00000000\"><div class=\"wptb-text-container wptb-ph-element wptb-element-text-7\" style=\"padding: 0px; margin: 0px; color: rgb(74, 85, 104); font-size: 15px;\"><div class=\"\" style=\"position: relative;\"><p style=\"text-align: center;\" class=\"\"><strong>Evaporazione<\/strong><\/p><\/div><\/div><\/td><td class=\"wptb-cell\" data-y-index=\"3\" data-x-index=\"1\" style=\"border-width: 1px; background-color: rgba(234, 240, 246, 0); border-style: solid; border-color: rgb(216, 216, 216);\" data-wptb-css-td-auto-width=\"true\" data-wptb-own-bg-color=\"#EAF0F600\"><div class=\"wptb-text-container wptb-ph-element wptb-element-text-16\" style=\"padding: 0px; margin: 0px; color: rgb(74, 85, 104); font-size: 15px;\"><div class=\"\" style=\"position: relative;\"><p style=\"text-align: center;\">2000kg\/h<\/p><\/div><\/div><\/td><\/tr><tr class=\"wptb-row\" style=\"background-color: rgb(255, 255, 255);\"><td class=\"wptb-cell\" data-y-index=\"4\" data-x-index=\"0\" style=\"border-width: 1px; border-style: solid; border-color: rgb(216, 216, 216); background-color: rgba(0, 0, 0, 0);\" data-wptb-css-td-auto-width=\"true\" data-wptb-own-bg-color=\"#00000000\"><div class=\"wptb-text-container wptb-ph-element wptb-element-text-44\" style=\"padding: 0px; margin: 0px; color: rgb(74, 85, 104); font-size: 15px;\"><div class=\"\" style=\"position: relative;\"><p style=\"text-align: center;\" class=\"\"><strong>Contenuto di umidit\u00e0 su base umida<\/strong><\/p><\/div><\/div><\/td><td class=\"wptb-cell\" data-y-index=\"4\" data-x-index=\"1\" style=\"border-width: 1px; background-color: rgba(234, 240, 246, 0); border-style: solid; border-color: rgb(216, 216, 216);\" data-wptb-css-td-auto-width=\"true\" data-wptb-own-bg-color=\"#EAF0F600\"><div class=\"wptb-text-container wptb-ph-element wptb-element-text-45\" style=\"padding: 0px; margin: 0px; color: rgb(74, 85, 104); font-size: 15px;\"><div class=\"\" style=\"position: relative;\"><p style=\"text-align: center;\">80% (acqua gratuita)<\/p><\/div><\/div><\/td><\/tr><tr class=\"wptb-row\" style=\"background-color: rgb(255, 255, 255);\"><td class=\"wptb-cell\" data-y-index=\"5\" data-x-index=\"0\" style=\"border-width: 1px; border-style: solid; border-color: rgb(216, 216, 216); background-color: rgba(0, 0, 0, 0);\" data-wptb-css-td-auto-width=\"true\" data-wptb-own-bg-color=\"#00000000\"><div class=\"wptb-text-container wptb-ph-element wptb-element-text-48\" style=\"padding: 0px; margin: 0px; color: rgb(74, 85, 104); font-size: 15px;\"><div class=\"\" style=\"position: relative;\"><p style=\"text-align: center;\" class=\"\"><strong>Contenuto di umidit\u00e0 su base secca<\/strong><\/p><\/div><\/div><\/td><td class=\"wptb-cell\" data-y-index=\"5\" data-x-index=\"1\" style=\"border-width: 1px; background-color: rgba(234, 240, 246, 0); border-style: solid; border-color: rgb(216, 216, 216);\" data-wptb-css-td-auto-width=\"true\" data-wptb-own-bg-color=\"#EAF0F600\"><div class=\"wptb-text-container wptb-ph-element wptb-element-text-49\" style=\"padding: 0px; margin: 0px; color: rgb(74, 85, 104); font-size: 15px;\"><div class=\"\" style=\"position: relative;\"><p style=\"text-align: center;\">\u22645% (acqua libera)<\/p><\/div><\/div><\/td><\/tr><tr class=\"wptb-row\" style=\"background-color: rgb(255, 255, 255);\"><td class=\"wptb-cell\" data-y-index=\"6\" data-x-index=\"0\" style=\"border-width: 1px; border-style: solid; border-color: rgb(216, 216, 216); background-color: rgba(0, 0, 0, 0);\" data-wptb-css-td-auto-width=\"true\" data-wptb-own-bg-color=\"#00000000\"><div class=\"wptb-text-container wptb-ph-element wptb-element-text-66\" style=\"padding: 0px; margin: 0px; color: rgb(74, 85, 104); font-size: 15px;\"><div class=\"\" style=\"position: relative;\"><p style=\"text-align: center;\" class=\"\"><strong>Peso specifico liquido<\/strong><\/p><\/div><\/div><\/td><td class=\"wptb-cell\" data-y-index=\"6\" data-x-index=\"1\" style=\"border-width: 1px; background-color: rgba(234, 240, 246, 0); border-style: solid; border-color: rgb(216, 216, 216);\" data-wptb-css-td-auto-width=\"true\" data-wptb-own-bg-color=\"#EAF0F600\"><div class=\"wptb-text-container wptb-ph-element wptb-element-text-67\" style=\"padding: 0px; margin: 0px; color: rgb(74, 85, 104); font-size: 15px;\"><div class=\"\" style=\"position: relative;\"><p style=\"text-align: center;\">1.03kg\/cm\u00b3<\/p><\/div><\/div><\/td><\/tr><tr class=\"wptb-row\" style=\"background-color: rgb(255, 255, 255);\"><td class=\"wptb-cell\" data-y-index=\"7\" data-x-index=\"0\" style=\"border-width: 1px; border-style: solid; border-color: rgb(216, 216, 216); background-color: rgba(0, 0, 0, 0);\" data-wptb-css-td-auto-width=\"true\" data-wptb-own-bg-color=\"#00000000\"><div class=\"wptb-text-container wptb-ph-element wptb-element-text-70\" style=\"padding: 0px; margin: 0px; color: rgb(74, 85, 104); font-size: 15px;\"><div class=\"\" style=\"position: relative;\"><p style=\"text-align: center;\"><strong>Temperatura di alimentazione<\/strong><\/p><\/div><\/div><\/td><td class=\"wptb-cell\" data-y-index=\"7\" data-x-index=\"1\" style=\"border-width: 1px; background-color: rgba(234, 240, 246, 0); border-style: solid; border-color: rgb(216, 216, 216);\" data-wptb-css-td-auto-width=\"true\" data-wptb-own-bg-color=\"#EAF0F600\"><div class=\"wptb-text-container wptb-ph-element wptb-element-text-71\" style=\"padding: 0px; margin: 0px; color: rgb(74, 85, 104); font-size: 15px;\"><div class=\"\" style=\"position: relative;\"><p style=\"text-align: center;\">40\u2103<\/p><\/div><\/div><\/td><\/tr><tr class=\"wptb-row\" style=\"background-color: rgb(255, 255, 255);\"><td class=\"wptb-cell\" data-y-index=\"8\" data-x-index=\"0\" style=\"border-width: 1px; border-style: solid; border-color: rgb(216, 216, 216); background-color: rgba(0, 0, 0, 0);\" data-wptb-css-td-auto-width=\"true\" data-wptb-own-bg-color=\"#00000000\"><div class=\"wptb-text-container wptb-ph-element wptb-element-text-254\" style=\"padding: 0px; margin: 0px; color: rgb(74, 85, 104); font-size: 15px;\"><div class=\"\" style=\"position: relative;\"><p style=\"text-align: center;\" class=\"\"><strong>Temperatura di scarico<\/strong><\/p><\/div><\/div><\/td><td class=\"wptb-cell\" data-y-index=\"8\" data-x-index=\"1\" style=\"border-width: 1px; background-color: rgba(234, 240, 246, 0); border-style: solid; border-color: rgb(216, 216, 216);\" data-wptb-css-td-auto-width=\"true\" data-wptb-own-bg-color=\"#EAF0F600\"><div class=\"wptb-text-container wptb-ph-element wptb-element-text-255\" style=\"padding: 0px; margin: 0px; color: rgb(74, 85, 104); font-size: 15px;\"><div class=\"\" style=\"position: relative;\"><p style=\"text-align: center;\">Circa 35 \u2103<\/p><\/div><\/div><\/td><\/tr><tr class=\"wptb-row\" style=\"background-color: rgb(255, 255, 255);\"><td class=\"wptb-cell\" data-y-index=\"9\" data-x-index=\"0\" style=\"border-width: 1px; border-style: solid; border-color: rgb(216, 216, 216); background-color: rgba(0, 0, 0, 0);\" data-wptb-css-td-auto-width=\"true\" data-wptb-own-bg-color=\"#00000000\"><div class=\"wptb-text-container wptb-ph-element wptb-element-text-256\" style=\"padding: 0px; margin: 0px; color: rgb(74, 85, 104); font-size: 15px;\"><div class=\"\" style=\"position: relative;\"><p style=\"text-align: center;\"><strong>Fonte di calore<\/strong><\/p><\/div><\/div><\/td><td class=\"wptb-cell\" data-y-index=\"9\" data-x-index=\"1\" style=\"border-width: 1px; background-color: rgba(234, 240, 246, 0); border-style: solid; border-color: rgb(216, 216, 216);\" data-wptb-css-td-auto-width=\"true\" data-wptb-own-bg-color=\"#EAF0F600\"><div class=\"wptb-text-container wptb-ph-element wptb-element-text-257\" style=\"padding: 0px; margin: 0px; color: rgb(74, 85, 104); font-size: 15px;\"><div class=\"\" style=\"position: relative;\"><p style=\"text-align: center;\">Vapore + riscaldamento elettrico<\/p><\/div><\/div><\/td><\/tr><tr class=\"wptb-row\" style=\"background-color: rgb(255, 255, 255);\"><td class=\"wptb-cell\" data-y-index=\"10\" data-x-index=\"0\" style=\"border-width: 1px; border-style: solid; border-color: rgb(216, 216, 216); background-color: rgba(0, 0, 0, 0);\" data-wptb-css-td-auto-width=\"true\" data-wptb-own-bg-color=\"#00000000\"><div class=\"wptb-text-container wptb-ph-element wptb-element-text-258\" style=\"padding: 0px; margin: 0px; color: rgb(74, 85, 104); font-size: 15px;\"><div class=\"\" style=\"position: relative;\"><p style=\"text-align: center;\" class=\"\"><strong>Metodo di ricezione<\/strong><\/p><\/div><\/div><\/td><td class=\"wptb-cell\" data-y-index=\"10\" data-x-index=\"1\" style=\"border-width: 1px; background-color: rgba(234, 240, 246, 0); border-style: solid; border-color: rgb(216, 216, 216);\" data-wptb-css-td-auto-width=\"true\" data-wptb-own-bg-color=\"#EAF0F600\"><div class=\"wptb-text-container wptb-ph-element wptb-element-text-259\" style=\"padding: 0px; margin: 0px; color: rgb(74, 85, 104); font-size: 15px;\"><div class=\"\" style=\"position: relative;\"><p style=\"text-align: center;\">Depolveratore a ciclone + film d'acqua<\/p><\/div><\/div><\/td><\/tr><tr class=\"wptb-row\" style=\"background-color: rgb(255, 255, 255);\"><td class=\"wptb-cell\" style=\"border-width: 1px; border-style: solid; border-color: rgb(216, 216, 216); background-color: rgb(217, 237, 247);\" data-x-index=\"0\" data-y-index=\"11\" data-wptb-css-td-auto-width=\"true\" colspan=\"2\" rowspan=\"1\" data-wptb-own-bg-color=\"#D9EDF7FF\"><div class=\"wptb-text-container wptb-ph-element wptb-element-text-160\" style=\"color: rgb(74, 85, 104); font-size: 17px; padding: 0px; margin: 0px;\"><div class=\"\" style=\"position: relative;\"><p style=\"text-align: center;\" class=\"\"><strong>2. Parametri tecnici della soluzione essiccante<\/strong><\/p><\/div><\/div><\/td><\/tr><tr class=\"wptb-row\" style=\"background-color: rgb(255, 255, 255);\"><td class=\"wptb-cell\" data-y-index=\"12\" data-x-index=\"0\" style=\"border-width: 1px; border-style: solid; border-color: rgb(216, 216, 216); background-color: rgba(0, 0, 0, 0);\" data-wptb-css-td-auto-width=\"true\" data-wptb-own-bg-color=\"#00000000\"><div class=\"wptb-text-container wptb-ph-element wptb-element-text-74\" style=\"padding: 0px; margin: 0px; color: rgb(74, 85, 104); font-size: 15px;\"><div class=\"\" style=\"position: relative;\"><p style=\"text-align: center;\" class=\"\"><strong>Modello di equipaggiamento<\/strong><\/p><\/div><\/div><\/td><td class=\"wptb-cell\" data-y-index=\"12\" data-x-index=\"1\" style=\"border-width: 1px; background-color: rgba(234, 240, 246, 0); border-style: solid; border-color: rgb(216, 216, 216);\" data-wptb-css-td-auto-width=\"true\" data-wptb-own-bg-color=\"#EAF0F600\"><div class=\"wptb-text-container wptb-ph-element wptb-element-text-75\" style=\"padding: 0px; margin: 0px; color: rgb(74, 85, 104); font-size: 15px;\"><div class=\"\" style=\"position: relative;\"><p style=\"text-align: center;\">Essiccatore a spruzzo centrifugo LPG-2000 *1<\/p><\/div><\/div><\/td><\/tr><tr class=\"wptb-row\" style=\"background-color: rgb(255, 255, 255);\"><td class=\"wptb-cell\" data-y-index=\"13\" data-x-index=\"0\" style=\"border-width: 1px; border-style: solid; border-color: rgb(216, 216, 216); background-color: rgba(0, 0, 0, 0);\" data-wptb-css-td-auto-width=\"true\" data-wptb-own-bg-color=\"#00000000\"><div class=\"wptb-text-container wptb-ph-element wptb-element-text-78\" style=\"padding: 0px; margin: 0px; color: rgb(74, 85, 104); font-size: 15px;\"><div class=\"\" style=\"position: relative;\"><p style=\"text-align: center;\" class=\"\"><strong>Metodo di atomizzazione<\/strong><\/p><\/div><\/div><\/td><td class=\"wptb-cell\" data-y-index=\"13\" data-x-index=\"1\" style=\"border-width: 1px; background-color: rgba(234, 240, 246, 0); border-style: solid; border-color: rgb(216, 216, 216);\" data-wptb-css-td-auto-width=\"true\" data-wptb-own-bg-color=\"#EAF0F600\"><div class=\"wptb-text-container wptb-ph-element wptb-element-text-79\" style=\"padding: 0px; margin: 0px; color: rgb(74, 85, 104); font-size: 15px;\"><div class=\"\" style=\"position: relative;\"><p style=\"text-align: center;\">Centrifugo<\/p><\/div><\/div><\/td><\/tr><tr class=\"wptb-row\" style=\"background-color: rgb(255, 255, 255);\"><td class=\"wptb-cell\" data-y-index=\"14\" data-x-index=\"0\" style=\"border-width: 1px; border-style: solid; border-color: rgb(216, 216, 216); background-color: rgba(0, 0, 0, 0);\" data-wptb-css-td-auto-width=\"true\" data-wptb-own-bg-color=\"#00000000\"><div class=\"wptb-text-container wptb-ph-element wptb-element-text-82\" style=\"padding: 0px; margin: 0px; color: rgb(74, 85, 104); font-size: 15px;\"><div class=\"\" style=\"position: relative;\"><p style=\"text-align: center;\" class=\"\"><strong>Metodo di contatto con aria calda<\/strong><\/p><\/div><\/div><\/td><td class=\"wptb-cell\" data-y-index=\"14\" data-x-index=\"1\" style=\"border-width: 1px; background-color: rgba(234, 240, 246, 0); border-style: solid; border-color: rgb(216, 216, 216);\" data-wptb-css-td-auto-width=\"true\" data-wptb-own-bg-color=\"#EAF0F600\"><div class=\"wptb-text-container wptb-ph-element wptb-element-text-83\" style=\"padding: 0px; margin: 0px; color: rgb(74, 85, 104); font-size: 15px;\"><div class=\"\" style=\"position: relative;\"><p style=\"text-align: center;\">Flusso parallelo<\/p><\/div><\/div><\/td><\/tr><tr class=\"wptb-row\" style=\"background-color: rgb(255, 255, 255);\"><td class=\"wptb-cell\" data-y-index=\"15\" data-x-index=\"0\" style=\"border-width: 1px; border-style: solid; border-color: rgb(216, 216, 216); background-color: rgba(0, 0, 0, 0);\" data-wptb-css-td-auto-width=\"true\" data-wptb-own-bg-color=\"#00000000\"><div class=\"wptb-text-container wptb-ph-element wptb-element-text-86\" style=\"padding: 0px; margin: 0px; color: rgb(74, 85, 104); font-size: 15px;\"><div class=\"\" style=\"position: relative;\"><p style=\"text-align: center;\" class=\"\"><strong>Temperatura dell'aria in ingresso<\/strong><\/p><\/div><\/div><\/td><td class=\"wptb-cell\" data-y-index=\"15\" data-x-index=\"1\" style=\"border-width: 1px; background-color: rgba(234, 240, 246, 0); border-style: solid; border-color: rgb(216, 216, 216);\" data-wptb-css-td-auto-width=\"true\" data-wptb-own-bg-color=\"#EAF0F600\"><div class=\"wptb-text-container wptb-ph-element wptb-element-text-87\" style=\"padding: 0px; margin: 0px; color: rgb(74, 85, 104); font-size: 15px;\"><div class=\"\" style=\"position: relative;\"><p style=\"text-align: center;\">160~220\u2103<\/p><\/div><\/div><\/td><\/tr><tr class=\"wptb-row\" style=\"background-color: rgb(255, 255, 255);\"><td class=\"wptb-cell\" data-y-index=\"16\" data-x-index=\"0\" style=\"border-width: 1px; border-style: solid; border-color: rgb(216, 216, 216); background-color: rgba(0, 0, 0, 0);\" data-wptb-css-td-auto-width=\"true\" data-wptb-own-bg-color=\"#00000000\"><div class=\"wptb-text-container wptb-ph-element wptb-element-text-90\" style=\"padding: 0px; margin: 0px; color: rgb(74, 85, 104); font-size: 15px;\"><div class=\"\" style=\"position: relative;\"><p style=\"text-align: center;\" class=\"\"><strong>Temperatura dell'aria in uscita<\/strong><\/p><\/div><\/div><\/td><td class=\"wptb-cell\" data-y-index=\"16\" data-x-index=\"1\" style=\"border-width: 1px; background-color: rgba(234, 240, 246, 0); border-style: solid; border-color: rgb(216, 216, 216);\" data-wptb-css-td-auto-width=\"true\" data-wptb-own-bg-color=\"#EAF0F600\"><div class=\"wptb-text-container wptb-ph-element wptb-element-text-91\" style=\"padding: 0px; margin: 0px; color: rgb(74, 85, 104); font-size: 15px;\"><div class=\"\" style=\"position: relative;\"><p style=\"text-align: center;\">80~100\u2103<\/p><\/div><\/div><\/td><\/tr><tr class=\"wptb-row\" style=\"background-color: rgb(255, 255, 255);\"><td class=\"wptb-cell\" data-y-index=\"17\" data-x-index=\"0\" style=\"border-width: 1px; border-style: solid; border-color: rgb(216, 216, 216); background-color: rgba(0, 0, 0, 0);\" data-wptb-css-td-auto-width=\"true\" data-wptb-own-bg-color=\"#00000000\"><div class=\"wptb-text-container wptb-ph-element wptb-element-text-94\" style=\"padding: 0px; margin: 0px; color: rgb(74, 85, 104); font-size: 15px;\"><div class=\"\" style=\"position: relative;\"><p style=\"text-align: center;\" class=\"\"><strong>Requisiti materiali<\/strong><\/p><\/div><\/div><\/td><td class=\"wptb-cell\" data-y-index=\"17\" data-x-index=\"1\" style=\"border-width: 1px; background-color: rgba(234, 240, 246, 0); border-style: solid; border-color: rgb(216, 216, 216);\" data-wptb-css-td-auto-width=\"true\" data-wptb-own-bg-color=\"#EAF0F600\"><div class=\"wptb-text-container wptb-ph-element wptb-element-text-95\" style=\"padding: 0px; margin: 0px; color: rgb(74, 85, 104); font-size: 15px;\"><div class=\"\" style=\"position: relative;\"><p style=\"text-align: center;\">Contatto del prodotto SUS304<\/p><\/div><\/div><\/td><\/tr><tr class=\"wptb-row\" style=\"background-color: rgb(255, 255, 255);\"><td class=\"wptb-cell\" data-y-index=\"18\" data-x-index=\"0\" style=\"border-width: 1px; border-style: solid; border-color: rgb(216, 216, 216); background-color: rgba(0, 0, 0, 0);\" data-wptb-css-td-auto-width=\"true\" data-wptb-own-bg-color=\"#00000000\"><div class=\"wptb-text-container wptb-ph-element wptb-element-text-98\" style=\"padding: 0px; margin: 0px; color: rgb(74, 85, 104); font-size: 15px;\"><div class=\"\" style=\"position: relative;\"><p style=\"text-align: center;\" class=\"\"><strong>Metodo di rimozione della polvere<\/strong><\/p><\/div><\/div><\/td><td class=\"wptb-cell\" data-y-index=\"18\" data-x-index=\"1\" style=\"border-width: 1px; background-color: rgba(234, 240, 246, 0); border-style: solid; border-color: rgb(216, 216, 216);\" data-wptb-css-td-auto-width=\"true\" data-wptb-own-bg-color=\"#EAF0F600\"><div class=\"wptb-text-container wptb-ph-element wptb-element-text-99\" style=\"padding: 0px; margin: 0px; color: rgb(74, 85, 104); font-size: 15px;\"><div class=\"\" style=\"position: relative;\"><p style=\"text-align: center;\">Separatore a ciclone<\/p><\/div><\/div><\/td><\/tr><tr class=\"wptb-row\" style=\"background-color: rgb(255, 255, 255);\"><td class=\"wptb-cell\" data-y-index=\"19\" data-x-index=\"0\" style=\"border-width: 1px; border-style: solid; border-color: rgb(216, 216, 216); background-color: rgba(0, 0, 0, 0);\" data-wptb-css-td-auto-width=\"true\" data-wptb-own-bg-color=\"#00000000\"><div class=\"wptb-text-container wptb-ph-element wptb-element-text-102\" style=\"padding: 0px; margin: 0px; color: rgb(74, 85, 104); font-size: 15px;\"><div class=\"\" style=\"position: relative;\"><p style=\"text-align: center;\"><strong>Metodo di riscaldamento<\/strong><\/p><\/div><\/div><\/td><td class=\"wptb-cell\" data-y-index=\"19\" data-x-index=\"1\" style=\"border-width: 1px; background-color: rgba(234, 240, 246, 0); border-style: solid; border-color: rgb(216, 216, 216);\" data-wptb-css-td-auto-width=\"true\" data-wptb-own-bg-color=\"#EAF0F600\"><div class=\"wptb-text-container wptb-ph-element wptb-element-text-103\" style=\"padding: 0px; margin: 0px; color: rgb(74, 85, 104); font-size: 15px;\"><div class=\"\" style=\"position: relative;\"><p style=\"text-align: center;\">Vapore + riscaldamento elettrico<\/p><\/div><\/div><\/td><\/tr><tr class=\"wptb-row\" style=\"background-color: rgb(255, 255, 255);\"><td class=\"wptb-cell\" data-y-index=\"20\" data-x-index=\"0\" style=\"border-width: 1px; border-style: solid; border-color: rgb(216, 216, 216); background-color: rgba(0, 0, 0, 0);\" data-wptb-css-td-auto-width=\"true\" data-wptb-own-bg-color=\"#00000000\"><div class=\"wptb-text-container wptb-ph-element wptb-element-text-106\" style=\"padding: 0px; margin: 0px; color: rgb(74, 85, 104); font-size: 15px;\"><div class=\"\" style=\"position: relative;\"><p style=\"text-align: center;\" class=\"\"><strong>Metodo di alimentazione<\/strong><\/p><\/div><\/div><\/td><td class=\"wptb-cell\" data-y-index=\"20\" data-x-index=\"1\" style=\"border-width: 1px; background-color: rgba(234, 240, 246, 0); border-style: solid; border-color: rgb(216, 216, 216);\" data-wptb-css-td-auto-width=\"true\" data-wptb-own-bg-color=\"#EAF0F600\"><div class=\"wptb-text-container wptb-ph-element wptb-element-text-107\" style=\"padding: 0px; margin: 0px; color: rgb(74, 85, 104); font-size: 15px;\"><div class=\"\" style=\"position: relative;\"><p style=\"text-align: center;\">Alimentazione con pompa a coclea<\/p><\/div><\/div><\/td><\/tr><tr class=\"wptb-row\" style=\"background-color: rgb(255, 255, 255);\"><td class=\"wptb-cell\" data-y-index=\"21\" data-x-index=\"0\" style=\"border-width: 1px; border-style: solid; border-color: rgb(216, 216, 216); background-color: rgba(0, 0, 0, 0);\" data-wptb-css-td-auto-width=\"true\" data-wptb-own-bg-color=\"#00000000\"><div class=\"wptb-text-container wptb-ph-element wptb-element-text-110\" style=\"padding: 0px; margin: 0px; color: rgb(74, 85, 104); font-size: 15px;\"><div class=\"\" style=\"position: relative;\"><p style=\"text-align: center;\" class=\"\"><strong>Sito di installazione<\/strong><\/p><\/div><\/div><\/td><td class=\"wptb-cell\" data-y-index=\"21\" data-x-index=\"1\" style=\"border-width: 1px; background-color: rgba(234, 240, 246, 0); border-style: solid; border-color: rgb(216, 216, 216);\" data-wptb-css-td-auto-width=\"true\" data-wptb-own-bg-color=\"#EAF0F600\"><div class=\"wptb-text-container wptb-ph-element wptb-element-text-111\" style=\"padding: 0px; margin: 0px; color: rgb(74, 85, 104); font-size: 15px;\"><div class=\"\" style=\"position: relative;\"><p style=\"text-align: center;\">Area generale per la torre principale, area pulita per il ricevimento dei materiali<\/p><\/div><grammarly-extension data-grammarly-shadow-root=\"true\" style=\"position: absolute; top: -1px; left: -1px; pointer-events: none; z-index: auto;\" class=\"cGcvT\"><\/grammarly-extension><grammarly-extension data-grammarly-shadow-root=\"true\" style=\"mix-blend-mode: darken; position: absolute; top: -1px; left: -1px; pointer-events: none; z-index: auto;\" class=\"cGcvT\"><\/grammarly-extension><grammarly-extension data-grammarly-shadow-root=\"true\" style=\"position: absolute; top: -1px; left: -1px; pointer-events: none; z-index: auto;\" class=\"cGcvT\"><\/grammarly-extension><grammarly-extension data-grammarly-shadow-root=\"true\" style=\"mix-blend-mode: darken; position: absolute; top: -1px; left: -1px; pointer-events: none; z-index: auto;\" class=\"cGcvT\"><\/grammarly-extension><\/div><\/td><\/tr><tr class=\"wptb-row\" style=\"background-color: rgb(255, 255, 255);\"><td class=\"wptb-cell\" data-y-index=\"22\" data-x-index=\"0\" style=\"border-width: 1px; border-style: solid; border-color: rgb(216, 216, 216); background-color: rgba(0, 0, 0, 0);\" data-wptb-css-td-auto-width=\"true\" data-wptb-own-bg-color=\"#00000000\"><div class=\"wptb-text-container wptb-ph-element wptb-element-text-260\" style=\"padding: 0px; margin: 0px; color: rgb(74, 85, 104); font-size: 15px;\"><div class=\"\" style=\"position: relative;\"><p style=\"text-align: center;\" class=\"\"><strong>Dimensioni del sito di installazione<\/strong><\/p><\/div><\/div><\/td><td class=\"wptb-cell\" data-y-index=\"22\" data-x-index=\"1\" style=\"border-width: 1px; background-color: rgba(234, 240, 246, 0); border-style: solid; border-color: rgb(216, 216, 216);\" data-wptb-css-td-auto-width=\"true\" data-wptb-own-bg-color=\"#EAF0F600\"><div class=\"wptb-text-container wptb-ph-element wptb-element-text-261\" style=\"padding: 0px; margin: 0px; color: rgb(74, 85, 104); font-size: 15px;\"><div class=\"\" style=\"position: relative;\"><p style=\"text-align: center;\">\u00c8 richiesto il disegno delle condizioni dell'impianto<\/p><\/div><grammarly-extension data-grammarly-shadow-root=\"true\" style=\"position: absolute; top: -1px; left: -1px; pointer-events: none; z-index: auto;\" class=\"cGcvT\"><\/grammarly-extension><grammarly-extension data-grammarly-shadow-root=\"true\" style=\"mix-blend-mode: darken; position: absolute; top: -1px; left: -1px; pointer-events: none; z-index: auto;\" class=\"cGcvT\"><\/grammarly-extension><\/div><\/td><\/tr><tr class=\"wptb-row\" style=\"background-color: rgb(255, 255, 255);\"><td class=\"wptb-cell\" data-y-index=\"23\" data-x-index=\"0\" style=\"border-width: 1px; border-style: solid; border-color: rgb(216, 216, 216); background-color: rgba(0, 0, 0, 0);\" data-wptb-css-td-auto-width=\"true\" data-wptb-own-bg-color=\"#00000000\"><div class=\"wptb-text-container wptb-ph-element wptb-element-text-262\" style=\"padding: 0px; margin: 0px; color: rgb(74, 85, 104); font-size: 15px;\"><div class=\"\" style=\"position: relative;\"><p style=\"text-align: center;\" class=\"\"><strong>Rumore<\/strong><\/p><\/div><\/div><\/td><td class=\"wptb-cell\" data-y-index=\"23\" data-x-index=\"1\" style=\"border-width: 1px; background-color: rgba(234, 240, 246, 0); border-style: solid; border-color: rgb(216, 216, 216);\" data-wptb-css-td-auto-width=\"true\" data-wptb-own-bg-color=\"#EAF0F600\"><div class=\"wptb-text-container wptb-ph-element wptb-element-text-263\" style=\"padding: 0px; margin: 0px; color: rgb(74, 85, 104); font-size: 15px;\"><div class=\"\" style=\"position: relative;\"><p style=\"text-align: center;\">\uff1c80 dB<\/p><\/div><grammarly-extension data-grammarly-shadow-root=\"true\" style=\"position: absolute; top: -1px; left: -1px; pointer-events: none; z-index: auto;\" class=\"cGcvT\"><\/grammarly-extension><grammarly-extension data-grammarly-shadow-root=\"true\" style=\"mix-blend-mode: darken; position: absolute; top: -1px; left: -1px; pointer-events: none; z-index: auto;\" class=\"cGcvT\"><\/grammarly-extension><\/div><\/td><\/tr><tr class=\"wptb-row\" style=\"background-color: rgb(255, 255, 255);\"><td class=\"wptb-cell\" style=\"border-width: 1px; border-style: solid; border-color: rgb(216, 216, 216); background-color: rgb(217, 237, 247);\" data-x-index=\"0\" data-y-index=\"24\" data-wptb-css-td-auto-width=\"true\" colspan=\"2\" rowspan=\"1\" data-wptb-own-bg-color=\"#D9EDF7FF\"><div class=\"wptb-text-container wptb-ph-element wptb-element-text-166\" style=\"color: rgb(74, 85, 104); font-size: 17px; padding: 0px; margin: 0px;\"><div class=\"\" style=\"position: relative;\"><p style=\"text-align: center;\" class=\"\"><strong>3. Condizioni dei lavori pubblici<\/strong><\/p><\/div><\/div><\/td><\/tr><tr class=\"wptb-row\" style=\"background-color: rgb(255, 255, 255);\"><td class=\"wptb-cell\" data-y-index=\"25\" data-x-index=\"0\" style=\"border-width: 1px; border-style: solid; border-color: rgb(216, 216, 216); background-color: rgba(0, 0, 0, 0);\" data-wptb-css-td-auto-width=\"true\" data-wptb-own-bg-color=\"#00000000\"><div class=\"wptb-text-container wptb-ph-element wptb-element-text-182\" style=\"padding: 0px; margin: 0px; color: rgb(74, 85, 104); font-size: 15px;\"><div class=\"\" style=\"position: relative;\"><p style=\"text-align: center;\" class=\"\"><strong>Pressione atmosferica<\/strong><\/p><\/div><\/div><\/td><td class=\"wptb-cell\" data-y-index=\"25\" data-x-index=\"1\" style=\"border-width: 1px; background-color: rgba(234, 240, 246, 0); border-style: solid; border-color: rgb(216, 216, 216);\" data-wptb-css-td-auto-width=\"true\" data-wptb-own-bg-color=\"#EAF0F600\"><div class=\"wptb-text-container wptb-ph-element wptb-element-text-183\" style=\"padding: 0px; margin: 0px; color: rgb(74, 85, 104); font-size: 15px;\"><div class=\"\" style=\"position: relative;\"><p style=\"text-align: center;\">101.3KPa<\/p><\/div><\/div><\/td><\/tr><tr class=\"wptb-row\" style=\"background-color: rgb(255, 255, 255);\"><td class=\"wptb-cell\" data-y-index=\"26\" data-x-index=\"0\" style=\"border-width: 1px; border-style: solid; border-color: rgb(216, 216, 216); background-color: rgba(0, 0, 0, 0);\" data-wptb-css-td-auto-width=\"true\" data-wptb-own-bg-color=\"#00000000\"><div class=\"wptb-text-container wptb-ph-element wptb-element-text-202\" style=\"padding: 0px; margin: 0px; color: rgb(74, 85, 104); font-size: 15px;\"><div class=\"\" style=\"position: relative;\"><p style=\"text-align: center;\" class=\"\"><strong>Temperatura ambiente<\/strong><\/p><\/div><\/div><\/td><td class=\"wptb-cell\" data-y-index=\"26\" data-x-index=\"1\" style=\"border-width: 1px; background-color: rgba(234, 240, 246, 0); border-style: solid; border-color: rgb(216, 216, 216);\" data-wptb-css-td-auto-width=\"true\" data-wptb-own-bg-color=\"#EAF0F600\"><div class=\"wptb-text-container wptb-ph-element wptb-element-text-203\" style=\"padding: 0px; margin: 0px; color: rgb(74, 85, 104); font-size: 15px;\"><div class=\"\" style=\"position: relative;\"><p style=\"text-align: center;\">10\u2103<\/p><\/div><\/div><\/td><\/tr><tr class=\"wptb-row\" style=\"background-color: rgb(255, 255, 255);\"><td class=\"wptb-cell\" data-y-index=\"27\" data-x-index=\"0\" style=\"border-width: 1px; border-style: solid; border-color: rgb(216, 216, 216); background-color: rgba(0, 0, 0, 0);\" data-wptb-css-td-auto-width=\"true\" data-wptb-own-bg-color=\"#00000000\"><div class=\"wptb-text-container wptb-ph-element wptb-element-text-197\" style=\"padding: 0px; margin: 0px; color: rgb(74, 85, 104); font-size: 15px;\"><div class=\"\" style=\"position: relative;\"><p style=\"text-align: center;\" class=\"\"><strong>Umidit\u00e0 relativa<\/strong><\/p><\/div><\/div><\/td><td class=\"wptb-cell\" data-y-index=\"27\" data-x-index=\"1\" style=\"border-width: 1px; background-color: rgba(234, 240, 246, 0); border-style: solid; border-color: rgb(216, 216, 216);\" data-wptb-css-td-auto-width=\"true\" data-wptb-own-bg-color=\"#EAF0F600\"><div class=\"wptb-text-container wptb-ph-element wptb-element-text-198\" style=\"padding: 0px; margin: 0px; color: rgb(74, 85, 104); font-size: 15px;\"><div class=\"\" style=\"position: relative;\"><p style=\"text-align: center;\">70%<\/p><\/div><\/div><\/td><\/tr><tr class=\"wptb-row\" style=\"background-color: rgb(255, 255, 255);\"><td class=\"wptb-cell\" data-y-index=\"28\" data-x-index=\"0\" style=\"border-width: 1px; border-style: solid; border-color: rgb(216, 216, 216); background-color: rgba(0, 0, 0, 0);\" data-wptb-css-td-auto-width=\"true\" data-wptb-own-bg-color=\"#00000000\"><div class=\"wptb-text-container wptb-ph-element wptb-element-text-192\" style=\"padding: 0px; margin: 0px; color: rgb(74, 85, 104); font-size: 15px;\"><div class=\"\" style=\"position: relative;\"><p style=\"text-align: center;\" class=\"\"><strong>Energia elettrica<\/strong><\/p><\/div><\/div><\/td><td class=\"wptb-cell\" data-y-index=\"28\" data-x-index=\"1\" style=\"border-width: 1px; background-color: rgba(234, 240, 246, 0); border-style: solid; border-color: rgb(216, 216, 216);\" data-wptb-css-td-auto-width=\"true\" data-wptb-own-bg-color=\"#EAF0F600\"><div class=\"wptb-text-container wptb-ph-element wptb-element-text-193\" style=\"padding: 0px; margin: 0px; color: rgb(74, 85, 104); font-size: 15px;\"><div class=\"\" style=\"position: relative;\"><p style=\"text-align: center;\">380V, trifase, 50Hz<\/p><\/div><\/div><\/td><\/tr><tr class=\"wptb-row\" style=\"background-color: rgb(255, 255, 255);\"><td class=\"wptb-cell\" data-y-index=\"29\" data-x-index=\"0\" style=\"border-width: 1px; border-style: solid; border-color: rgb(216, 216, 216); background-color: rgba(0, 0, 0, 0);\" data-wptb-css-td-auto-width=\"true\" data-wptb-own-bg-color=\"#00000000\"><div class=\"wptb-text-container wptb-ph-element wptb-element-text-207\" style=\"padding: 0px; margin: 0px; color: rgb(74, 85, 104); font-size: 15px;\"><div class=\"\" style=\"position: relative;\"><p style=\"text-align: center;\"><strong>Potenza della macchina<\/strong><\/p><\/div><\/div><\/td><td class=\"wptb-cell\" data-y-index=\"29\" data-x-index=\"1\" style=\"border-width: 1px; background-color: rgba(234, 240, 246, 0); border-style: solid; border-color: rgb(216, 216, 216);\" data-wptb-css-td-auto-width=\"true\" data-wptb-own-bg-color=\"#EAF0F600\"><div class=\"wptb-text-container wptb-ph-element wptb-element-text-208\" style=\"padding: 0px; margin: 0px; color: rgb(74, 85, 104); font-size: 15px;\"><div class=\"\" style=\"position: relative;\"><p style=\"text-align: center;\">Circa 230 KW<\/p><\/div><\/div><\/td><\/tr><tr class=\"wptb-row\" style=\"background-color: rgb(255, 255, 255);\"><td class=\"wptb-cell\" data-y-index=\"30\" data-x-index=\"0\" style=\"border-width: 1px; border-style: solid; border-color: rgb(216, 216, 216); background-color: rgba(0, 0, 0, 0);\" data-wptb-css-td-auto-width=\"true\" data-wptb-own-bg-color=\"#00000000\"><div class=\"wptb-text-container wptb-ph-element wptb-element-text-212\" style=\"padding: 0px; margin: 0px; color: rgb(74, 85, 104); font-size: 15px;\"><div class=\"\" style=\"position: relative;\"><p style=\"text-align: center;\"><strong>Consumo di aria compressa<\/strong><\/p><\/div><\/div><\/td><td class=\"wptb-cell\" data-y-index=\"30\" data-x-index=\"1\" style=\"border-width: 1px; background-color: rgba(234, 240, 246, 0); border-style: solid; border-color: rgb(216, 216, 216);\" data-wptb-css-td-auto-width=\"true\" data-wptb-own-bg-color=\"#EAF0F600\"><div class=\"wptb-text-container wptb-ph-element wptb-element-text-213\" style=\"padding: 0px; margin: 0px; color: rgb(74, 85, 104); font-size: 15px;\"><div class=\"\" style=\"position: relative;\"><p style=\"text-align: center;\">0.6m\u00b3\/min<\/p><\/div><\/div><\/td><\/tr><tr class=\"wptb-row\" style=\"background-color: rgb(255, 255, 255);\"><td class=\"wptb-cell\" data-y-index=\"31\" data-x-index=\"0\" style=\"border-width: 1px; border-style: solid; border-color: rgb(216, 216, 216); background-color: rgba(0, 0, 0, 0);\" data-wptb-css-td-auto-width=\"true\" data-wptb-own-bg-color=\"#00000000\"><div class=\"wptb-text-container wptb-ph-element wptb-element-text-217\" style=\"padding: 0px; margin: 0px; color: rgb(74, 85, 104); font-size: 15px;\"><div class=\"\" style=\"position: relative;\"><p style=\"text-align: center;\"><strong>Consumo di vapore<\/strong><\/p><\/div><\/div><\/td><td class=\"wptb-cell\" data-y-index=\"31\" data-x-index=\"1\" style=\"border-width: 1px; background-color: rgba(234, 240, 246, 0); border-style: solid; border-color: rgb(216, 216, 216);\" data-wptb-css-td-auto-width=\"true\" data-wptb-own-bg-color=\"#EAF0F600\"><div class=\"wptb-text-container wptb-ph-element wptb-element-text-218\" style=\"padding: 0px; margin: 0px; color: rgb(74, 85, 104); font-size: 15px;\"><div class=\"\" style=\"position: relative;\"><p style=\"text-align: center;\">Circa 3500kg\/h<\/p><\/div><\/div><\/td><\/tr><tr class=\"wptb-row\" style=\"background-color: rgb(255, 255, 255);\"><td class=\"wptb-cell\" data-y-index=\"32\" data-x-index=\"0\" style=\"border-width: 1px; border-style: solid; border-color: rgb(216, 216, 216); background-color: rgba(0, 0, 0, 0);\" data-wptb-css-td-auto-width=\"true\" data-wptb-own-bg-color=\"#00000000\"><div class=\"wptb-text-container wptb-ph-element wptb-element-text-222\" style=\"padding: 0px; margin: 0px; color: rgb(74, 85, 104); font-size: 15px;\"><div class=\"\" style=\"position: relative;\"><p style=\"text-align: center;\"><strong>Pressione dell'aria compressa<\/strong><\/p><\/div><\/div><\/td><td class=\"wptb-cell\" data-y-index=\"32\" data-x-index=\"1\" style=\"border-width: 1px; background-color: rgba(234, 240, 246, 0); border-style: solid; border-color: rgb(216, 216, 216);\" data-wptb-css-td-auto-width=\"true\" data-wptb-own-bg-color=\"#EAF0F600\"><div class=\"wptb-text-container wptb-ph-element wptb-element-text-223\" style=\"padding: 0px; margin: 0px; color: rgb(74, 85, 104); font-size: 15px;\"><div class=\"\" style=\"position: relative;\"><p style=\"text-align: center;\">0.3~0.6mpa<\/p><\/div><\/div><\/td><\/tr><\/tbody><\/table>\n<\/div>\n\n<p><strong>3. La nostra soluzione essiccante per essiccamento a spruzzo centrifugo TPG-1000 per proteine idrolizzate di pesce<\/strong><\/p>\n<div class=\"wptb-container-legacy\" data-table-id=\"9301\">\n    <table class=\"wptb-preview-table wptb-element-main-table_setting-2909 edit-active\" data-reconstraction=\"0\" style=\"border: 1px solid rgb(216, 216, 216); display: table;\" data-wptb-table-tds-sum-max-width=\"263.5\" data-wptb-cells-width-auto-count=\"2\" role=\"table\" data-wptb-header-background-color=\"#ffffff\" data-table-columns=\"2\" data-wptb-table-directives=\"eyJpbm5lckJvcmRlcnMiOnsiYWN0aXZlIjoiYWxsIiwiYm9yZGVyV2lkdGgiOiIxIiwiYm9yZGVyUmFkaXVzZXMiOnsiYWxsIjpudWxsfX19\" data-wptb-extra-styles=\"LndwdGItcmliYm9uX2VsZW1lbnQtY29udGFpbmVyIHsKICB0b3A6IC03JTsKfQogIA==\" data-wptb-responsive-directives=\"eyJyZXNwb25zaXZlRW5hYmxlZCI6dHJ1ZSwicmVzcG9uc2l2ZU1vZGUiOiJhdXRvIiwicHJlc2VydmVSb3dDb2xvciI6ZmFsc2UsInJlbGF0aXZlV2lkdGgiOiJ3aW5kb3ciLCJoZWFkZXJGdWxseU1lcmdlZCI6ZmFsc2UsIm1vZGVPcHRpb25zIjp7ImF1dG8iOnsiZGlzYWJsZWQiOnsiZGVza3RvcCI6ZmFsc2UsInRhYmxldCI6ZmFsc2UsIm1vYmlsZSI6ZmFsc2V9LCJ0b3BSb3dBc0hlYWRlciI6eyJkZXNrdG9wIjpmYWxzZSwidGFibGV0Ijp0cnVlLCJtb2JpbGUiOmZhbHNlfSwicmVwZWF0TWVyZ2VkSGVhZGVyIjp7ImRlc2t0b3AiOnRydWUsInRhYmxldCI6dHJ1ZSwibW9iaWxlIjp0cnVlfSwic3RhdGljVG9wUm93Ijp7ImRlc2t0b3AiOmZhbHNlLCJ0YWJsZXQiOmZhbHNlLCJtb2JpbGUiOmZhbHNlfSwiY2VsbFN0YWNrRGlyZWN0aW9uIjp7ImRlc2t0b3AiOiJyb3ciLCJ0YWJsZXQiOiJyb3ciLCJtb2JpbGUiOiJjb2x1bW4ifSwiY2VsbHNQZXJSb3ciOnsiZGVza3RvcCI6MSwidGFibGV0IjoxLCJtb2JpbGUiOjF9fX0sImJyZWFrcG9pbnRzIjp7ImRlc2t0b3AiOnsibmFtZSI6ImRlc2t0b3AiLCJ3aWR0aCI6MTAyNH0sInRhYmxldCI6eyJuYW1lIjoidGFibGV0Iiwid2lkdGgiOjcwMH0sIm1vYmlsZSI6eyJuYW1lIjoibW9iaWxlIiwid2lkdGgiOjMwMH19fQ==\" data-wptb-adaptive-table=\"0\" data-wptb-even-row-background-color=\"#FFFFFFFF\" data-wptb-odd-row-background-color=\"#FFFFFFFF\" data-wptb-horizontal-scroll-status=\"false\" data-wptb-fixed-width-size=\"0\"><tbody><tr class=\"wptb-row\" style=\"background-color: rgb(255, 255, 255);\"><td class=\"wptb-cell\" style=\"border-width: 1px; border-style: solid; border-color: rgb(216, 216, 216); background-color: rgb(217, 237, 247);\" data-x-index=\"0\" data-y-index=\"0\" data-wptb-css-td-auto-width=\"true\" colspan=\"2\" rowspan=\"1\" data-wptb-own-bg-color=\"#D9EDF7FF\"><div class=\"wptb-text-container wptb-ph-element wptb-element-text-153\" style=\"color: rgb(74, 85, 104); font-size: 17px; padding: 0px; margin: 0px;\"><div class=\"\" style=\"position: relative;\"><p style=\"text-align: center;\"><strong>1. Materiali e requisiti del cliente<\/strong><\/p><\/div><\/div><\/td><\/tr><tr class=\"wptb-row\" data-wptb-bg-color=\"\" style=\"background-color: rgb(255, 255, 255);\"><td class=\"wptb-cell\" data-y-index=\"1\" data-x-index=\"0\" style=\"border-width: 1px; border-style: solid; border-color: rgb(216, 216, 216); background-color: rgba(0, 0, 0, 0);\" data-wptb-css-td-auto-width=\"true\" data-wptb-own-bg-color=\"#00000000\"><div class=\"wptb-text-container wptb-ph-element wptb-element-text-5\" style=\"padding: 0px; margin: 0px; color: rgb(74, 85, 104); font-size: 15px;\"><div class=\"\" style=\"position: relative;\"><p style=\"text-align: center;\"><strong>Materiale<\/strong><\/p><\/div><\/div><\/td><td class=\"wptb-cell\" data-y-index=\"1\" data-x-index=\"1\" style=\"border-width: 1px; background-color: rgba(234, 240, 246, 0); border-style: solid; border-color: rgb(216, 216, 216);\" data-wptb-css-td-auto-width=\"true\" data-wptb-own-bg-color=\"#EAF0F600\"><div class=\"wptb-text-container wptb-ph-element wptb-element-text-15\" style=\"padding: 0px; margin: 0px; color: rgb(74, 85, 104); font-size: 15px;\"><div class=\"\" style=\"position: relative;\"><p style=\"text-align: center;\">Proteine \u200b\u200bidrolizzate di pesce<\/p><\/div><\/div><\/td><\/tr><tr class=\"wptb-row\" data-wptb-bg-color=\"\" style=\"background-color: rgb(255, 255, 255);\"><td class=\"wptb-cell\" data-y-index=\"2\" data-x-index=\"0\" style=\"border-width: 1px; border-style: solid; border-color: rgb(216, 216, 216); background-color: rgba(0, 0, 0, 0);\" data-wptb-css-td-auto-width=\"true\" data-wptb-own-bg-color=\"#00000000\"><div class=\"wptb-text-container wptb-ph-element wptb-element-text-6\" style=\"padding: 0px; margin: 0px; color: rgb(74, 85, 104); font-size: 15px;\"><div class=\"\" style=\"position: relative;\"><p style=\"text-align: center;\"><strong>Stato di umidit\u00e0<\/strong><\/p><\/div><\/div><\/td><td class=\"wptb-cell\" data-y-index=\"2\" data-x-index=\"1\" style=\"border-width: 1px; background-color: rgba(234, 240, 246, 0); border-style: solid; border-color: rgb(216, 216, 216);\" data-wptb-css-td-auto-width=\"true\" data-wptb-own-bg-color=\"#EAF0F600\"><div class=\"wptb-text-container wptb-ph-element wptb-element-text-41\" style=\"color: rgb(74, 85, 104); font-size: 15px; padding: 0px; margin: 0px;\"><div class=\"\" style=\"position: relative;\"><p style=\"text-align: center;\">Acqua gratis<\/p><\/div><\/div><\/td><\/tr><tr class=\"wptb-row\" data-wptb-bg-color=\"\" style=\"background-color: rgb(255, 255, 255);\"><td class=\"wptb-cell\" data-y-index=\"3\" data-x-index=\"0\" style=\"border-width: 1px; border-style: solid; border-color: rgb(216, 216, 216); background-color: rgba(0, 0, 0, 0);\" data-wptb-css-td-auto-width=\"true\" data-wptb-own-bg-color=\"#00000000\"><div class=\"wptb-text-container wptb-ph-element wptb-element-text-7\" style=\"padding: 0px; margin: 0px; color: rgb(74, 85, 104); font-size: 15px;\"><div class=\"\" style=\"position: relative;\"><p style=\"text-align: center;\"><strong>Evaporazione<\/strong><\/p><\/div><\/div><\/td><td class=\"wptb-cell\" data-y-index=\"3\" data-x-index=\"1\" style=\"border-width: 1px; background-color: rgba(234, 240, 246, 0); border-style: solid; border-color: rgb(216, 216, 216);\" data-wptb-css-td-auto-width=\"true\" data-wptb-own-bg-color=\"#EAF0F600\"><div class=\"wptb-text-container wptb-ph-element wptb-element-text-16\" style=\"padding: 0px; margin: 0px; color: rgb(74, 85, 104); font-size: 15px;\"><div class=\"\" style=\"position: relative;\"><p style=\"text-align: center;\">circa 1000kg\/h<\/p><\/div><\/div><\/td><\/tr><tr class=\"wptb-row\" style=\"background-color: rgb(255, 255, 255);\"><td class=\"wptb-cell\" data-y-index=\"4\" data-x-index=\"0\" style=\"border-width: 1px; border-style: solid; border-color: rgb(216, 216, 216); background-color: rgba(0, 0, 0, 0);\" data-wptb-css-td-auto-width=\"true\" data-wptb-own-bg-color=\"#00000000\"><div class=\"wptb-text-container wptb-ph-element wptb-element-text-44\" style=\"padding: 0px; margin: 0px; color: rgb(74, 85, 104); font-size: 15px;\"><div class=\"\" style=\"position: relative;\"><p style=\"text-align: center;\"><strong>Contenuto di umidit\u00e0 della base bagnata<\/strong><\/p><\/div><\/div><\/td><td class=\"wptb-cell\" data-y-index=\"4\" data-x-index=\"1\" style=\"border-width: 1px; background-color: rgba(234, 240, 246, 0); border-style: solid; border-color: rgb(216, 216, 216);\" data-wptb-css-td-auto-width=\"true\" data-wptb-own-bg-color=\"#EAF0F600\"><div class=\"wptb-text-container wptb-ph-element wptb-element-text-45\" style=\"padding: 0px; margin: 0px; color: rgb(74, 85, 104); font-size: 15px;\"><div class=\"\" style=\"position: relative;\"><p style=\"text-align: center;\">79% (acqua gratuita)<\/p><\/div><\/div><\/td><\/tr><tr class=\"wptb-row\" style=\"background-color: rgb(255, 255, 255);\"><td class=\"wptb-cell\" data-y-index=\"5\" data-x-index=\"0\" style=\"border-width: 1px; border-style: solid; border-color: rgb(216, 216, 216); background-color: rgba(0, 0, 0, 0);\" data-wptb-css-td-auto-width=\"true\" data-wptb-own-bg-color=\"#00000000\"><div class=\"wptb-text-container wptb-ph-element wptb-element-text-48\" style=\"padding: 0px; margin: 0px; color: rgb(74, 85, 104); font-size: 15px;\"><div class=\"\" style=\"position: relative;\"><p style=\"text-align: center;\"><strong>Contenuto di umidit\u00e0 della base secca<\/strong><\/p><\/div><\/div><\/td><td class=\"wptb-cell\" data-y-index=\"5\" data-x-index=\"1\" style=\"border-width: 1px; background-color: rgba(234, 240, 246, 0); border-style: solid; border-color: rgb(216, 216, 216);\" data-wptb-css-td-auto-width=\"true\" data-wptb-own-bg-color=\"#EAF0F600\"><div class=\"wptb-text-container wptb-ph-element wptb-element-text-49\" style=\"padding: 0px; margin: 0px; color: rgb(74, 85, 104); font-size: 15px;\"><div class=\"\" style=\"position: relative;\"><p style=\"text-align: center;\">\u22643% (acqua libera)<\/p><\/div><\/div><\/td><\/tr><tr class=\"wptb-row\" style=\"background-color: rgb(255, 255, 255);\"><td class=\"wptb-cell\" data-y-index=\"6\" data-x-index=\"0\" style=\"border-width: 1px; border-style: solid; border-color: rgb(216, 216, 216); background-color: rgba(0, 0, 0, 0);\" data-wptb-css-td-auto-width=\"true\" data-wptb-own-bg-color=\"#00000000\"><div class=\"wptb-text-container wptb-ph-element wptb-element-text-66\" style=\"padding: 0px; margin: 0px; color: rgb(74, 85, 104); font-size: 15px;\"><div class=\"\" style=\"position: relative;\"><p style=\"text-align: center;\"><strong>Peso specifico liquido<\/strong><\/p><\/div><\/div><\/td><td class=\"wptb-cell\" data-y-index=\"6\" data-x-index=\"1\" style=\"border-width: 1px; background-color: rgba(234, 240, 246, 0); border-style: solid; border-color: rgb(216, 216, 216);\" data-wptb-css-td-auto-width=\"true\" data-wptb-own-bg-color=\"#EAF0F600\"><div class=\"wptb-text-container wptb-ph-element wptb-element-text-67\" style=\"padding: 0px; margin: 0px; color: rgb(74, 85, 104); font-size: 15px;\"><div class=\"\" style=\"position: relative;\"><p style=\"text-align: center;\">1.04kg\/cm\u00b3<\/p><\/div><\/div><\/td><\/tr><tr class=\"wptb-row\" style=\"background-color: rgb(255, 255, 255);\"><td class=\"wptb-cell\" data-y-index=\"7\" data-x-index=\"0\" style=\"border-width: 1px; border-style: solid; border-color: rgb(216, 216, 216); background-color: rgba(0, 0, 0, 0);\" data-wptb-css-td-auto-width=\"true\" data-wptb-own-bg-color=\"#00000000\"><div class=\"wptb-text-container wptb-ph-element wptb-element-text-70\" style=\"padding: 0px; margin: 0px; color: rgb(74, 85, 104); font-size: 15px;\"><div class=\"\" style=\"position: relative;\"><p style=\"text-align: center;\"><strong>Temperatura di alimentazione<\/strong><\/p><\/div><\/div><\/td><td class=\"wptb-cell\" data-y-index=\"7\" data-x-index=\"1\" style=\"border-width: 1px; background-color: rgba(234, 240, 246, 0); border-style: solid; border-color: rgb(216, 216, 216);\" data-wptb-css-td-auto-width=\"true\" data-wptb-own-bg-color=\"#EAF0F600\"><div class=\"wptb-text-container wptb-ph-element wptb-element-text-71\" style=\"padding: 0px; margin: 0px; color: rgb(74, 85, 104); font-size: 15px;\"><div class=\"\" style=\"position: relative;\"><p style=\"text-align: center;\">10~12\u2103<\/p><\/div><\/div><\/td><\/tr><tr class=\"wptb-row\" style=\"background-color: rgb(255, 255, 255);\"><td class=\"wptb-cell\" data-y-index=\"8\" data-x-index=\"0\" style=\"border-width: 1px; border-style: solid; border-color: rgb(216, 216, 216); background-color: rgba(0, 0, 0, 0);\" data-wptb-css-td-auto-width=\"true\" data-wptb-own-bg-color=\"#00000000\"><div class=\"wptb-text-container wptb-ph-element wptb-element-text-254\" style=\"padding: 0px; margin: 0px; color: rgb(74, 85, 104); font-size: 15px;\"><div class=\"\" style=\"position: relative;\"><p style=\"text-align: center;\"><strong>Temperatura di scarico<\/strong><\/p><\/div><\/div><\/td><td class=\"wptb-cell\" data-y-index=\"8\" data-x-index=\"1\" style=\"border-width: 1px; background-color: rgba(234, 240, 246, 0); border-style: solid; border-color: rgb(216, 216, 216);\" data-wptb-css-td-auto-width=\"true\" data-wptb-own-bg-color=\"#EAF0F600\"><div class=\"wptb-text-container wptb-ph-element wptb-element-text-255\" style=\"padding: 0px; margin: 0px; color: rgb(74, 85, 104); font-size: 15px;\"><div class=\"\" style=\"position: relative;\"><p style=\"text-align: center;\">circa 35\u2103<\/p><\/div><\/div><\/td><\/tr><tr class=\"wptb-row\" style=\"background-color: rgb(255, 255, 255);\"><td class=\"wptb-cell\" data-y-index=\"9\" data-x-index=\"0\" style=\"border-width: 1px; border-style: solid; border-color: rgb(216, 216, 216); background-color: rgba(0, 0, 0, 0);\" data-wptb-css-td-auto-width=\"true\" data-wptb-own-bg-color=\"#00000000\"><div class=\"wptb-text-container wptb-ph-element wptb-element-text-256\" style=\"padding: 0px; margin: 0px; color: rgb(74, 85, 104); font-size: 15px;\"><div class=\"\" style=\"position: relative;\"><p style=\"text-align: center;\"><strong>Fonte di calore<\/strong><\/p><\/div><\/div><\/td><td class=\"wptb-cell\" data-y-index=\"9\" data-x-index=\"1\" style=\"border-width: 1px; background-color: rgba(234, 240, 246, 0); border-style: solid; border-color: rgb(216, 216, 216);\" data-wptb-css-td-auto-width=\"true\" data-wptb-own-bg-color=\"#EAF0F600\"><div class=\"wptb-text-container wptb-ph-element wptb-element-text-257\" style=\"padding: 0px; margin: 0px; color: rgb(74, 85, 104); font-size: 15px;\"><div class=\"\" style=\"position: relative;\"><p style=\"text-align: center;\">Stufa ad aria calda a gas<\/p><\/div><\/div><\/td><\/tr><tr class=\"wptb-row\" style=\"background-color: rgb(255, 255, 255);\"><td class=\"wptb-cell\" data-y-index=\"10\" data-x-index=\"0\" style=\"border-width: 1px; border-style: solid; border-color: rgb(216, 216, 216); background-color: rgba(0, 0, 0, 0);\" data-wptb-css-td-auto-width=\"true\" data-wptb-own-bg-color=\"#00000000\"><div class=\"wptb-text-container wptb-ph-element wptb-element-text-258\" style=\"padding: 0px; margin: 0px; color: rgb(74, 85, 104); font-size: 15px;\"><div class=\"\" style=\"position: relative;\"><p style=\"text-align: center;\"><strong>Metodo di ricezione<\/strong><\/p><\/div><\/div><\/td><td class=\"wptb-cell\" data-y-index=\"10\" data-x-index=\"1\" style=\"border-width: 1px; background-color: rgba(234, 240, 246, 0); border-style: solid; border-color: rgb(216, 216, 216);\" data-wptb-css-td-auto-width=\"true\" data-wptb-own-bg-color=\"#EAF0F600\"><div class=\"wptb-text-container wptb-ph-element wptb-element-text-259\" style=\"padding: 0px; margin: 0px; color: rgb(74, 85, 104); font-size: 15px;\"><div class=\"\" style=\"position: relative;\"><p style=\"text-align: center;\">Collettore a ciclone a due stadi<\/p><\/div><\/div><\/td><\/tr><tr class=\"wptb-row\" style=\"background-color: rgb(255, 255, 255);\"><td class=\"wptb-cell\" style=\"border-width: 1px; border-style: solid; border-color: rgb(216, 216, 216); background-color: rgb(217, 237, 247);\" data-x-index=\"0\" data-y-index=\"11\" data-wptb-css-td-auto-width=\"true\" colspan=\"2\" rowspan=\"1\" data-wptb-own-bg-color=\"#D9EDF7FF\"><div class=\"wptb-text-container wptb-ph-element wptb-element-text-160\" style=\"color: rgb(74, 85, 104); font-size: 17px; padding: 0px; margin: 0px;\"><div class=\"\" style=\"position: relative;\"><p style=\"text-align: center;\"><strong>2. I nostri parametri tecnici della soluzione di essiccazione<\/strong><\/p><\/div><\/div><\/td><\/tr><tr class=\"wptb-row\" style=\"background-color: rgb(255, 255, 255);\"><td class=\"wptb-cell\" data-y-index=\"12\" data-x-index=\"0\" style=\"border-width: 1px; border-style: solid; border-color: rgb(216, 216, 216); background-color: rgba(0, 0, 0, 0);\" data-wptb-css-td-auto-width=\"true\" data-wptb-own-bg-color=\"#00000000\"><div class=\"wptb-text-container wptb-ph-element wptb-element-text-74\" style=\"padding: 0px; margin: 0px; color: rgb(74, 85, 104); font-size: 15px;\"><div class=\"\" style=\"position: relative;\"><p style=\"text-align: center;\"><strong>Modello di equipaggiamento<\/strong><\/p><\/div><\/div><\/td><td class=\"wptb-cell\" data-y-index=\"12\" data-x-index=\"1\" style=\"border-width: 1px; background-color: rgba(234, 240, 246, 0); border-style: solid; border-color: rgb(216, 216, 216);\" data-wptb-css-td-auto-width=\"true\" data-wptb-own-bg-color=\"#EAF0F600\"><div class=\"wptb-text-container wptb-ph-element wptb-element-text-75\" style=\"padding: 0px; margin: 0px; color: rgb(74, 85, 104); font-size: 15px;\"><div class=\"\" style=\"position: relative;\"><p style=\"text-align: center;\">Essiccatore a spruzzo centrifugo TPG-1000 *1<\/p><\/div><\/div><\/td><\/tr><tr class=\"wptb-row\" style=\"background-color: rgb(255, 255, 255);\"><td class=\"wptb-cell\" data-y-index=\"13\" data-x-index=\"0\" style=\"border-width: 1px; border-style: solid; border-color: rgb(216, 216, 216); background-color: rgba(0, 0, 0, 0);\" data-wptb-css-td-auto-width=\"true\" data-wptb-own-bg-color=\"#00000000\"><div class=\"wptb-text-container wptb-ph-element wptb-element-text-78\" style=\"padding: 0px; margin: 0px; color: rgb(74, 85, 104); font-size: 15px;\"><div class=\"\" style=\"position: relative;\"><p style=\"text-align: center;\"><strong>Metodo di atomizzazione<\/strong><\/p><\/div><\/div><\/td><td class=\"wptb-cell\" data-y-index=\"13\" data-x-index=\"1\" style=\"border-width: 1px; background-color: rgba(234, 240, 246, 0); border-style: solid; border-color: rgb(216, 216, 216);\" data-wptb-css-td-auto-width=\"true\" data-wptb-own-bg-color=\"#EAF0F600\"><div class=\"wptb-text-container wptb-ph-element wptb-element-text-79\" style=\"padding: 0px; margin: 0px; color: rgb(74, 85, 104); font-size: 15px;\"><div class=\"\" style=\"position: relative;\"><p style=\"text-align: center;\">Centrifugo<\/p><\/div><\/div><\/td><\/tr><tr class=\"wptb-row\" style=\"background-color: rgb(255, 255, 255);\"><td class=\"wptb-cell\" data-y-index=\"14\" data-x-index=\"0\" style=\"border-width: 1px; border-style: solid; border-color: rgb(216, 216, 216); background-color: rgba(0, 0, 0, 0);\" data-wptb-css-td-auto-width=\"true\" data-wptb-own-bg-color=\"#00000000\"><div class=\"wptb-text-container wptb-ph-element wptb-element-text-82\" style=\"padding: 0px; margin: 0px; color: rgb(74, 85, 104); font-size: 15px;\"><div class=\"\" style=\"position: relative;\"><p style=\"text-align: center;\"><strong>Metodo di contatto con aria calda<\/strong><\/p><\/div><\/div><\/td><td class=\"wptb-cell\" data-y-index=\"14\" data-x-index=\"1\" style=\"border-width: 1px; background-color: rgba(234, 240, 246, 0); border-style: solid; border-color: rgb(216, 216, 216);\" data-wptb-css-td-auto-width=\"true\" data-wptb-own-bg-color=\"#EAF0F600\"><div class=\"wptb-text-container wptb-ph-element wptb-element-text-83\" style=\"padding: 0px; margin: 0px; color: rgb(74, 85, 104); font-size: 15px;\"><div class=\"\" style=\"position: relative;\"><p style=\"text-align: center;\">Flusso parallelo<\/p><\/div><\/div><\/td><\/tr><tr class=\"wptb-row\" style=\"background-color: rgb(255, 255, 255);\"><td class=\"wptb-cell\" data-y-index=\"15\" data-x-index=\"0\" style=\"border-width: 1px; border-style: solid; border-color: rgb(216, 216, 216); background-color: rgba(0, 0, 0, 0);\" data-wptb-css-td-auto-width=\"true\" data-wptb-own-bg-color=\"#00000000\"><div class=\"wptb-text-container wptb-ph-element wptb-element-text-86\" style=\"padding: 0px; margin: 0px; color: rgb(74, 85, 104); font-size: 15px;\"><div class=\"\" style=\"position: relative;\"><p style=\"text-align: center;\"><strong>Temperatura dell'aria in ingresso<\/strong><\/p><\/div><\/div><\/td><td class=\"wptb-cell\" data-y-index=\"15\" data-x-index=\"1\" style=\"border-width: 1px; background-color: rgba(234, 240, 246, 0); border-style: solid; border-color: rgb(216, 216, 216);\" data-wptb-css-td-auto-width=\"true\" data-wptb-own-bg-color=\"#EAF0F600\"><div class=\"wptb-text-container wptb-ph-element wptb-element-text-87\" style=\"padding: 0px; margin: 0px; color: rgb(74, 85, 104); font-size: 15px;\"><div class=\"\" style=\"position: relative;\"><p style=\"text-align: center;\">160~220\u2103<\/p><\/div><\/div><\/td><\/tr><tr class=\"wptb-row\" style=\"background-color: rgb(255, 255, 255);\"><td class=\"wptb-cell\" data-y-index=\"16\" data-x-index=\"0\" style=\"border-width: 1px; border-style: solid; border-color: rgb(216, 216, 216); background-color: rgba(0, 0, 0, 0);\" data-wptb-css-td-auto-width=\"true\" data-wptb-own-bg-color=\"#00000000\"><div class=\"wptb-text-container wptb-ph-element wptb-element-text-90\" style=\"padding: 0px; margin: 0px; color: rgb(74, 85, 104); font-size: 15px;\"><div class=\"\" style=\"position: relative;\"><p style=\"text-align: center;\"><strong>Temperatura dell'aria in uscita<\/strong><\/p><\/div><\/div><\/td><td class=\"wptb-cell\" data-y-index=\"16\" data-x-index=\"1\" style=\"border-width: 1px; background-color: rgba(234, 240, 246, 0); border-style: solid; border-color: rgb(216, 216, 216);\" data-wptb-css-td-auto-width=\"true\" data-wptb-own-bg-color=\"#EAF0F600\"><div class=\"wptb-text-container wptb-ph-element wptb-element-text-91\" style=\"padding: 0px; margin: 0px; color: rgb(74, 85, 104); font-size: 15px;\"><div class=\"\" style=\"position: relative;\"><p style=\"text-align: center;\">80~100\u2103<\/p><\/div><\/div><\/td><\/tr><tr class=\"wptb-row\" style=\"background-color: rgb(255, 255, 255);\"><td class=\"wptb-cell\" data-y-index=\"17\" data-x-index=\"0\" style=\"border-width: 1px; border-style: solid; border-color: rgb(216, 216, 216); background-color: rgba(0, 0, 0, 0);\" data-wptb-css-td-auto-width=\"true\" data-wptb-own-bg-color=\"#00000000\"><div class=\"wptb-text-container wptb-ph-element wptb-element-text-94\" style=\"padding: 0px; margin: 0px; color: rgb(74, 85, 104); font-size: 15px;\"><div class=\"\" style=\"position: relative;\"><p style=\"text-align: center;\"><strong>Requisiti materiali<\/strong><\/p><\/div><\/div><\/td><td class=\"wptb-cell\" data-y-index=\"17\" data-x-index=\"1\" style=\"border-width: 1px; background-color: rgba(234, 240, 246, 0); border-style: solid; border-color: rgb(216, 216, 216);\" data-wptb-css-td-auto-width=\"true\" data-wptb-own-bg-color=\"#EAF0F600\"><div class=\"wptb-text-container wptb-ph-element wptb-element-text-95\" style=\"padding: 0px; margin: 0px; color: rgb(74, 85, 104); font-size: 15px;\"><div class=\"\" style=\"position: relative;\"><p style=\"text-align: center;\">Contatto del prodotto SUS304<\/p><\/div><\/div><\/td><\/tr><tr class=\"wptb-row\" style=\"background-color: rgb(255, 255, 255);\"><td class=\"wptb-cell\" data-y-index=\"18\" data-x-index=\"0\" style=\"border-width: 1px; border-style: solid; border-color: rgb(216, 216, 216); background-color: rgba(0, 0, 0, 0);\" data-wptb-css-td-auto-width=\"true\" data-wptb-own-bg-color=\"#00000000\"><div class=\"wptb-text-container wptb-ph-element wptb-element-text-98\" style=\"padding: 0px; margin: 0px; color: rgb(74, 85, 104); font-size: 15px;\"><div class=\"\" style=\"position: relative;\"><p style=\"text-align: center;\" class=\"\"><strong>Metodo di rimozione della polvere<\/strong><\/p><\/div><\/div><\/td><td class=\"wptb-cell\" data-y-index=\"18\" data-x-index=\"1\" style=\"border-width: 1px; background-color: rgba(234, 240, 246, 0); border-style: solid; border-color: rgb(216, 216, 216);\" data-wptb-css-td-auto-width=\"true\" data-wptb-own-bg-color=\"#EAF0F600\"><div class=\"wptb-text-container wptb-ph-element wptb-element-text-99\" style=\"padding: 0px; margin: 0px; color: rgb(74, 85, 104); font-size: 15px;\"><div class=\"\" style=\"position: relative;\"><p style=\"text-align: center;\">Separatore a ciclone<\/p><\/div><\/div><\/td><\/tr><tr class=\"wptb-row\" style=\"background-color: rgb(255, 255, 255);\"><td class=\"wptb-cell\" data-y-index=\"19\" data-x-index=\"0\" style=\"border-width: 1px; border-style: solid; border-color: rgb(216, 216, 216); background-color: rgba(0, 0, 0, 0);\" data-wptb-css-td-auto-width=\"true\" data-wptb-own-bg-color=\"#00000000\"><div class=\"wptb-text-container wptb-ph-element wptb-element-text-102\" style=\"padding: 0px; margin: 0px; color: rgb(74, 85, 104); font-size: 15px;\"><div class=\"\" style=\"position: relative;\"><p style=\"text-align: center;\"><strong>Metodo di riscaldamento<\/strong><\/p><\/div><\/div><\/td><td class=\"wptb-cell\" data-y-index=\"19\" data-x-index=\"1\" style=\"border-width: 1px; background-color: rgba(234, 240, 246, 0); border-style: solid; border-color: rgb(216, 216, 216);\" data-wptb-css-td-auto-width=\"true\" data-wptb-own-bg-color=\"#EAF0F600\"><div class=\"wptb-text-container wptb-ph-element wptb-element-text-103\" style=\"padding: 0px; margin: 0px; color: rgb(74, 85, 104); font-size: 15px;\"><div class=\"\" style=\"position: relative;\"><p style=\"text-align: center;\">Stufa ad aria calda a gas<\/p><\/div><\/div><\/td><\/tr><tr class=\"wptb-row\" style=\"background-color: rgb(255, 255, 255);\"><td class=\"wptb-cell\" data-y-index=\"20\" data-x-index=\"0\" style=\"border-width: 1px; border-style: solid; border-color: rgb(216, 216, 216); background-color: rgba(0, 0, 0, 0);\" data-wptb-css-td-auto-width=\"true\" data-wptb-own-bg-color=\"#00000000\"><div class=\"wptb-text-container wptb-ph-element wptb-element-text-106\" style=\"padding: 0px; margin: 0px; color: rgb(74, 85, 104); font-size: 15px;\"><div class=\"\" style=\"position: relative;\"><p style=\"text-align: center;\"><strong>Metodo di alimentazione<\/strong><\/p><\/div><\/div><\/td><td class=\"wptb-cell\" data-y-index=\"20\" data-x-index=\"1\" style=\"border-width: 1px; background-color: rgba(234, 240, 246, 0); border-style: solid; border-color: rgb(216, 216, 216);\" data-wptb-css-td-auto-width=\"true\" data-wptb-own-bg-color=\"#EAF0F600\"><div class=\"wptb-text-container wptb-ph-element wptb-element-text-107\" style=\"padding: 0px; margin: 0px; color: rgb(74, 85, 104); font-size: 15px;\"><div class=\"\" style=\"position: relative;\"><p style=\"text-align: center;\">Alimentazione con pompa a coclea<\/p><\/div><\/div><\/td><\/tr><tr class=\"wptb-row\" style=\"background-color: rgb(255, 255, 255);\"><td class=\"wptb-cell\" data-y-index=\"21\" data-x-index=\"0\" style=\"border-width: 1px; border-style: solid; border-color: rgb(216, 216, 216); background-color: rgba(0, 0, 0, 0);\" data-wptb-css-td-auto-width=\"true\" data-wptb-own-bg-color=\"#00000000\"><div class=\"wptb-text-container wptb-ph-element wptb-element-text-110\" style=\"padding: 0px; margin: 0px; color: rgb(74, 85, 104); font-size: 15px;\"><div class=\"\" style=\"position: relative;\"><p style=\"text-align: center;\"><strong>Sito di installazione<\/strong><\/p><\/div><\/div><\/td><td class=\"wptb-cell\" data-y-index=\"21\" data-x-index=\"1\" style=\"border-width: 1px; background-color: rgba(234, 240, 246, 0); border-style: solid; border-color: rgb(216, 216, 216);\" data-wptb-css-td-auto-width=\"true\" data-wptb-own-bg-color=\"#EAF0F600\"><div class=\"wptb-text-container wptb-ph-element wptb-element-text-111\" style=\"padding: 0px; margin: 0px; color: rgb(74, 85, 104); font-size: 15px;\"><div class=\"\" style=\"position: relative;\"><p style=\"text-align: center;\">Area generale per la torre principale, area pulita per il ricevimento dei materiali<\/p><\/div><grammarly-extension data-grammarly-shadow-root=\"true\" style=\"position: absolute; top: -1px; left: -1px; pointer-events: none; z-index: auto;\" class=\"cGcvT\"><\/grammarly-extension><grammarly-extension data-grammarly-shadow-root=\"true\" style=\"mix-blend-mode: darken; position: absolute; top: -1px; left: -1px; pointer-events: none; z-index: auto;\" class=\"cGcvT\"><\/grammarly-extension><\/div><\/td><\/tr><tr class=\"wptb-row\" style=\"background-color: rgb(255, 255, 255);\"><td class=\"wptb-cell\" data-y-index=\"22\" data-x-index=\"0\" style=\"border-width: 1px; border-style: solid; border-color: rgb(216, 216, 216); background-color: rgba(0, 0, 0, 0);\" data-wptb-css-td-auto-width=\"true\" data-wptb-own-bg-color=\"#00000000\"><div class=\"wptb-text-container wptb-ph-element wptb-element-text-260\" style=\"padding: 0px; margin: 0px; color: rgb(74, 85, 104); font-size: 15px;\"><div class=\"\" style=\"position: relative;\"><p style=\"text-align: center;\"><strong>Dimensioni del sito di installazione<\/strong><\/p><\/div><\/div><\/td><td class=\"wptb-cell\" data-y-index=\"22\" data-x-index=\"1\" style=\"border-width: 1px; background-color: rgba(234, 240, 246, 0); border-style: solid; border-color: rgb(216, 216, 216);\" data-wptb-css-td-auto-width=\"true\" data-wptb-own-bg-color=\"#EAF0F600\"><div class=\"wptb-text-container wptb-ph-element wptb-element-text-261\" style=\"padding: 0px; margin: 0px; color: rgb(74, 85, 104); font-size: 15px;\"><div class=\"\" style=\"position: relative;\"><p style=\"text-align: center;\">\u00c8 richiesto il disegno delle condizioni dell'impianto<\/p><\/div><grammarly-extension data-grammarly-shadow-root=\"true\" style=\"position: absolute; top: -1px; left: -1px; pointer-events: none; z-index: auto;\" class=\"cGcvT\"><\/grammarly-extension><grammarly-extension data-grammarly-shadow-root=\"true\" style=\"mix-blend-mode: darken; position: absolute; top: -1px; left: -1px; pointer-events: none; z-index: auto;\" class=\"cGcvT\"><\/grammarly-extension><\/div><\/td><\/tr><tr class=\"wptb-row\" style=\"background-color: rgb(255, 255, 255);\"><td class=\"wptb-cell\" data-y-index=\"23\" data-x-index=\"0\" style=\"border-width: 1px; border-style: solid; border-color: rgb(216, 216, 216); background-color: rgba(0, 0, 0, 0);\" data-wptb-css-td-auto-width=\"true\" data-wptb-own-bg-color=\"#00000000\"><div class=\"wptb-text-container wptb-ph-element wptb-element-text-262\" style=\"padding: 0px; margin: 0px; color: rgb(74, 85, 104); font-size: 15px;\"><div class=\"\" style=\"position: relative;\"><p style=\"text-align: center;\"><strong>Rumore<\/strong><\/p><\/div><\/div><\/td><td class=\"wptb-cell\" data-y-index=\"23\" data-x-index=\"1\" style=\"border-width: 1px; background-color: rgba(234, 240, 246, 0); border-style: solid; border-color: rgb(216, 216, 216);\" data-wptb-css-td-auto-width=\"true\" data-wptb-own-bg-color=\"#EAF0F600\"><div class=\"wptb-text-container wptb-ph-element wptb-element-text-263\" style=\"padding: 0px; margin: 0px; color: rgb(74, 85, 104); font-size: 15px;\"><div class=\"\" style=\"position: relative;\"><p style=\"text-align: center;\">\uff1c80 dB<\/p><\/div><grammarly-extension data-grammarly-shadow-root=\"true\" style=\"position: absolute; top: -1px; left: -1px; pointer-events: none; z-index: auto;\" class=\"cGcvT\"><\/grammarly-extension><grammarly-extension data-grammarly-shadow-root=\"true\" style=\"mix-blend-mode: darken; position: absolute; top: -1px; left: -1px; pointer-events: none; z-index: auto;\" class=\"cGcvT\"><\/grammarly-extension><\/div><\/td><\/tr><tr class=\"wptb-row\" style=\"background-color: rgb(255, 255, 255);\"><td class=\"wptb-cell\" style=\"border-width: 1px; border-style: solid; border-color: rgb(216, 216, 216); background-color: rgb(217, 237, 247);\" data-x-index=\"0\" data-y-index=\"24\" data-wptb-css-td-auto-width=\"true\" colspan=\"2\" rowspan=\"1\" data-wptb-own-bg-color=\"#D9EDF7FF\"><div class=\"wptb-text-container wptb-ph-element wptb-element-text-166\" style=\"color: rgb(74, 85, 104); font-size: 17px; padding: 0px; margin: 0px;\"><div class=\"\" style=\"position: relative;\"><p style=\"text-align: center;\"><strong>3. Condizioni dei lavori pubblici<\/strong><\/p><\/div><\/div><\/td><\/tr><tr class=\"wptb-row\" style=\"background-color: rgb(255, 255, 255);\"><td class=\"wptb-cell\" data-y-index=\"25\" data-x-index=\"0\" style=\"border-width: 1px; border-style: solid; border-color: rgb(216, 216, 216); background-color: rgba(0, 0, 0, 0);\" data-wptb-css-td-auto-width=\"true\" data-wptb-own-bg-color=\"#00000000\"><div class=\"wptb-text-container wptb-ph-element wptb-element-text-182\" style=\"padding: 0px; margin: 0px; color: rgb(74, 85, 104); font-size: 15px;\"><div class=\"\" style=\"position: relative;\"><p style=\"text-align: center;\"><strong>Pressione atmosferica<\/strong><\/p><\/div><\/div><\/td><td class=\"wptb-cell\" data-y-index=\"25\" data-x-index=\"1\" style=\"border-width: 1px; background-color: rgba(234, 240, 246, 0); border-style: solid; border-color: rgb(216, 216, 216);\" data-wptb-css-td-auto-width=\"true\" data-wptb-own-bg-color=\"#EAF0F600\"><div class=\"wptb-text-container wptb-ph-element wptb-element-text-183\" style=\"padding: 0px; margin: 0px; color: rgb(74, 85, 104); font-size: 15px;\"><div class=\"\" style=\"position: relative;\"><p style=\"text-align: center;\">101.3KPa<\/p><\/div><\/div><\/td><\/tr><tr class=\"wptb-row\" style=\"background-color: rgb(255, 255, 255);\"><td class=\"wptb-cell\" data-y-index=\"26\" data-x-index=\"0\" style=\"border-width: 1px; border-style: solid; border-color: rgb(216, 216, 216); background-color: rgba(0, 0, 0, 0);\" data-wptb-css-td-auto-width=\"true\" data-wptb-own-bg-color=\"#00000000\"><div class=\"wptb-text-container wptb-ph-element wptb-element-text-202\" style=\"padding: 0px; margin: 0px; color: rgb(74, 85, 104); font-size: 15px;\"><div class=\"\" style=\"position: relative;\"><p style=\"text-align: center;\"><strong>Temperatura ambiente<\/strong><\/p><\/div><\/div><\/td><td class=\"wptb-cell\" data-y-index=\"26\" data-x-index=\"1\" style=\"border-width: 1px; background-color: rgba(234, 240, 246, 0); border-style: solid; border-color: rgb(216, 216, 216);\" data-wptb-css-td-auto-width=\"true\" data-wptb-own-bg-color=\"#EAF0F600\"><div class=\"wptb-text-container wptb-ph-element wptb-element-text-203\" style=\"padding: 0px; margin: 0px; color: rgb(74, 85, 104); font-size: 15px;\"><div class=\"\" style=\"position: relative;\"><p style=\"text-align: center;\">10\u2103<\/p><\/div><\/div><\/td><\/tr><tr class=\"wptb-row\" style=\"background-color: rgb(255, 255, 255);\"><td class=\"wptb-cell\" data-y-index=\"27\" data-x-index=\"0\" style=\"border-width: 1px; border-style: solid; border-color: rgb(216, 216, 216); background-color: rgba(0, 0, 0, 0);\" data-wptb-css-td-auto-width=\"true\" data-wptb-own-bg-color=\"#00000000\"><div class=\"wptb-text-container wptb-ph-element wptb-element-text-197\" style=\"padding: 0px; margin: 0px; color: rgb(74, 85, 104); font-size: 15px;\"><div class=\"\" style=\"position: relative;\"><p style=\"text-align: center;\"><strong>Umidit\u00e0 relativa<\/strong><\/p><\/div><\/div><\/td><td class=\"wptb-cell\" data-y-index=\"27\" data-x-index=\"1\" style=\"border-width: 1px; background-color: rgba(234, 240, 246, 0); border-style: solid; border-color: rgb(216, 216, 216);\" data-wptb-css-td-auto-width=\"true\" data-wptb-own-bg-color=\"#EAF0F600\"><div class=\"wptb-text-container wptb-ph-element wptb-element-text-198\" style=\"padding: 0px; margin: 0px; color: rgb(74, 85, 104); font-size: 15px;\"><div class=\"\" style=\"position: relative;\"><p style=\"text-align: center;\">70%<\/p><\/div><\/div><\/td><\/tr><tr class=\"wptb-row\" style=\"background-color: rgb(255, 255, 255);\"><td class=\"wptb-cell\" data-y-index=\"28\" data-x-index=\"0\" style=\"border-width: 1px; border-style: solid; border-color: rgb(216, 216, 216); background-color: rgba(0, 0, 0, 0);\" data-wptb-css-td-auto-width=\"true\" data-wptb-own-bg-color=\"#00000000\"><div class=\"wptb-text-container wptb-ph-element wptb-element-text-192\" style=\"padding: 0px; margin: 0px; color: rgb(74, 85, 104); font-size: 15px;\"><div class=\"\" style=\"position: relative;\"><p style=\"text-align: center;\"><strong>Energia elettrica<\/strong><\/p><\/div><\/div><\/td><td class=\"wptb-cell\" data-y-index=\"28\" data-x-index=\"1\" style=\"border-width: 1px; background-color: rgba(234, 240, 246, 0); border-style: solid; border-color: rgb(216, 216, 216);\" data-wptb-css-td-auto-width=\"true\" data-wptb-own-bg-color=\"#EAF0F600\"><div class=\"wptb-text-container wptb-ph-element wptb-element-text-193\" style=\"padding: 0px; margin: 0px; color: rgb(74, 85, 104); font-size: 15px;\"><div class=\"\" style=\"position: relative;\"><p style=\"text-align: center;\">380V, trifase, 50Hz<\/p><\/div><\/div><\/td><\/tr><tr class=\"wptb-row\" style=\"background-color: rgb(255, 255, 255);\"><td class=\"wptb-cell\" data-y-index=\"29\" data-x-index=\"0\" style=\"border-width: 1px; border-style: solid; border-color: rgb(216, 216, 216); background-color: rgba(0, 0, 0, 0);\" data-wptb-css-td-auto-width=\"true\" data-wptb-own-bg-color=\"#00000000\"><div class=\"wptb-text-container wptb-ph-element wptb-element-text-207\" style=\"padding: 0px; margin: 0px; color: rgb(74, 85, 104); font-size: 15px;\"><div class=\"\" style=\"position: relative;\"><p style=\"text-align: center;\"><strong>Potenza della macchina<\/strong><\/p><\/div><\/div><\/td><td class=\"wptb-cell\" data-y-index=\"29\" data-x-index=\"1\" style=\"border-width: 1px; background-color: rgba(234, 240, 246, 0); border-style: solid; border-color: rgb(216, 216, 216);\" data-wptb-css-td-auto-width=\"true\" data-wptb-own-bg-color=\"#EAF0F600\"><div class=\"wptb-text-container wptb-ph-element wptb-element-text-208\" style=\"padding: 0px; margin: 0px; color: rgb(74, 85, 104); font-size: 15px;\"><div class=\"\" style=\"position: relative;\"><p style=\"text-align: center;\">120KW<\/p><\/div><\/div><\/td><\/tr><tr class=\"wptb-row\" style=\"background-color: rgb(255, 255, 255);\"><td class=\"wptb-cell\" data-y-index=\"30\" data-x-index=\"0\" style=\"border-width: 1px; border-style: solid; border-color: rgb(216, 216, 216); background-color: rgba(0, 0, 0, 0);\" data-wptb-css-td-auto-width=\"true\" data-wptb-own-bg-color=\"#00000000\"><div class=\"wptb-text-container wptb-ph-element wptb-element-text-212\" style=\"padding: 0px; margin: 0px; color: rgb(74, 85, 104); font-size: 15px;\"><div class=\"\" style=\"position: relative;\"><p style=\"text-align: center;\"><strong>Consumo di aria compressa<\/strong><\/p><\/div><\/div><\/td><td class=\"wptb-cell\" data-y-index=\"30\" data-x-index=\"1\" style=\"border-width: 1px; background-color: rgba(234, 240, 246, 0); border-style: solid; border-color: rgb(216, 216, 216);\" data-wptb-css-td-auto-width=\"true\" data-wptb-own-bg-color=\"#EAF0F600\"><div class=\"wptb-text-container wptb-ph-element wptb-element-text-213\" style=\"padding: 0px; margin: 0px; color: rgb(74, 85, 104); font-size: 15px;\"><div class=\"\" style=\"position: relative;\"><p style=\"text-align: center;\">1.1m\u00b3\/min<\/p><\/div><\/div><\/td><\/tr><tr class=\"wptb-row\" style=\"background-color: rgb(255, 255, 255);\"><td class=\"wptb-cell\" data-y-index=\"31\" data-x-index=\"0\" style=\"border-width: 1px; border-style: solid; border-color: rgb(216, 216, 216); background-color: rgba(0, 0, 0, 0);\" data-wptb-css-td-auto-width=\"true\" data-wptb-own-bg-color=\"#00000000\"><div class=\"wptb-text-container wptb-ph-element wptb-element-text-217\" style=\"padding: 0px; margin: 0px; color: rgb(74, 85, 104); font-size: 15px;\"><div class=\"\" style=\"position: relative;\"><p style=\"text-align: center;\"><strong>Consumo di gas naturale<\/strong><\/p><\/div><\/div><\/td><td class=\"wptb-cell\" data-y-index=\"31\" data-x-index=\"1\" style=\"border-width: 1px; background-color: rgba(234, 240, 246, 0); border-style: solid; border-color: rgb(216, 216, 216);\" data-wptb-css-td-auto-width=\"true\" data-wptb-own-bg-color=\"#EAF0F600\"><div class=\"wptb-text-container wptb-ph-element wptb-element-text-218\" style=\"padding: 0px; margin: 0px; color: rgb(74, 85, 104); font-size: 15px;\"><div class=\"\" style=\"position: relative;\"><p style=\"text-align: center;\">circa 116Nm\u00b3 \/h<\/p><\/div><\/div><\/td><\/tr><tr class=\"wptb-row\" style=\"background-color: rgb(255, 255, 255);\"><td class=\"wptb-cell\" data-y-index=\"32\" data-x-index=\"0\" style=\"border-width: 1px; border-style: solid; border-color: rgb(216, 216, 216); background-color: rgba(0, 0, 0, 0);\" data-wptb-css-td-auto-width=\"true\" data-wptb-own-bg-color=\"#00000000\"><div class=\"wptb-text-container wptb-ph-element wptb-element-text-222\" style=\"padding: 0px; margin: 0px; color: rgb(74, 85, 104); font-size: 15px;\"><div class=\"\" style=\"position: relative;\"><p style=\"text-align: center;\"><strong>Pressione dell'aria compressa<\/strong><\/p><\/div><\/div><\/td><td class=\"wptb-cell\" data-y-index=\"32\" data-x-index=\"1\" style=\"border-width: 1px; background-color: rgba(234, 240, 246, 0); border-style: solid; border-color: rgb(216, 216, 216);\" data-wptb-css-td-auto-width=\"true\" data-wptb-own-bg-color=\"#EAF0F600\"><div class=\"wptb-text-container wptb-ph-element wptb-element-text-223\" style=\"padding: 0px; margin: 0px; color: rgb(74, 85, 104); font-size: 15px;\"><div class=\"\" style=\"position: relative;\"><p style=\"text-align: center;\">0.3~0.6mpa<\/p><\/div><\/div><\/td><\/tr><\/tbody><\/table>\n<\/div>\n\n","protected":false},"excerpt":{"rendered":"<p>Il nostro sistema di essiccazione centrifuga a spruzzo \u00e8 composto da sistema di alimentazione, sistema di aria calda, sistema di essiccazione (voluta di ingresso + torre di essiccazione), sistema di rimozione della polvere (separatore a ciclone primario e secondario + sistema di ricezione), sistema di pulizia e sistema di controllo.<\/p>\n<p>Di solito \u00e8 stato utilizzato per l&#8217;essiccazione di materiali, come cibo, lievito, biancospino, collagene, estratto di medicinali, albume\/tuorlo, proteine plasmatiche\/cellule del sangue, aminoacidi, aromi, fluoruro di sodio, polvere di lattice e altro ancora.<\/p>\n<p>Di seguito sono riportate le nostre soluzioni di essiccazione per composti nutritivi, succo di mango e idrolizzato di proteine di pesce.<\/p>\n<p>Possiamo personalizzare schemi di essiccazione specifici in base ai vostri materiali e requisiti.<\/p>\n","protected":false},"featured_media":5861,"template":"","meta":{"site-sidebar-layout":"default","site-content-layout":"default","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"default","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}}},"product_brand":[],"product_cat":[182],"product_tag":[],"class_list":["post-5860","product","type-product","status-publish","has-post-thumbnail","product_cat-essiccatore-a-spruzzo","desktop-align-center","tablet-align-center","mobile-align-center","ast-product-gallery-layout-horizontal","ast-product-gallery-with-no-image","ast-product-tabs-layout-horizontal","ast-qv-on-image","first","instock","shipping-taxable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/www.griffinmachinery.com\/it\/wp-json\/wp\/v2\/product\/5860","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.griffinmachinery.com\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.griffinmachinery.com\/it\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.griffinmachinery.com\/it\/wp-json\/wp\/v2\/media\/5861"}],"wp:attachment":[{"href":"https:\/\/www.griffinmachinery.com\/it\/wp-json\/wp\/v2\/media?parent=5860"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.griffinmachinery.com\/it\/wp-json\/wp\/v2\/product_brand?post=5860"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.griffinmachinery.com\/it\/wp-json\/wp\/v2\/product_cat?post=5860"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.griffinmachinery.com\/it\/wp-json\/wp\/v2\/product_tag?post=5860"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}